{"id":37,"count":40,"description":"","link":"https:\/\/elbeaterio.es\/index.php\/category\/el-beaterio\/beaterios-2010-2011\/","name":"Beaterios 2010-2011","slug":"beaterios-2010-2011","taxonomy":"category","parent":3,"meta":[],"_links":{"self":[{"href":"https:\/\/elbeaterio.es\/index.php\/wp-json\/wp\/v2\/categories\/37","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elbeaterio.es\/index.php\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/elbeaterio.es\/index.php\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/elbeaterio.es\/index.php\/wp-json\/wp\/v2\/categories\/3"}],"wp:post_type":[{"href":"https:\/\/elbeaterio.es\/index.php\/wp-json\/wp\/v2\/posts?categories=37"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}