{"id":59,"count":45,"description":"","link":"https:\/\/elbeaterio.es\/index.php\/category\/el-beaterio\/beaterios-2014-2015\/","name":"Beaterios 2014-2015","slug":"beaterios-2014-2015","taxonomy":"category","parent":3,"meta":[],"_links":{"self":[{"href":"https:\/\/elbeaterio.es\/index.php\/wp-json\/wp\/v2\/categories\/59","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elbeaterio.es\/index.php\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/elbeaterio.es\/index.php\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/elbeaterio.es\/index.php\/wp-json\/wp\/v2\/categories\/3"}],"wp:post_type":[{"href":"https:\/\/elbeaterio.es\/index.php\/wp-json\/wp\/v2\/posts?categories=59"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}