{"id":143,"date":"2010-11-28T00:00:00","date_gmt":"2010-11-28T00:00:00","guid":{"rendered":"http:\/\/localhost\/joomla\/2010\/11\/28\/icon-el-cazo-buscando-hasta-el-final-del-puchero\/"},"modified":"2025-05-29T19:37:35","modified_gmt":"2025-05-29T17:37:35","slug":"icon-el-cazo-buscando-hasta-el-final-del-puchero","status":"publish","type":"post","link":"https:\/\/elbeaterio.es\/index.php\/2010\/11\/28\/icon-el-cazo-buscando-hasta-el-final-del-puchero\/","title":{"rendered":"\u00a1Con el cazo buscando hasta el final del puchero!"},"content":{"rendered":"\n<figure class=\" wp-block-table eplus-wrapper\"><table><thead><tr><th class=\"has-text-align-center\" data-align=\"center\">Sporting de Gij\u00f3n 1-3 Real Sociedad<\/th><\/tr><\/thead><tbody><tr><td class=\"has-text-align-center\" data-align=\"center\">Jornada 13 &#8211; 28\/11\/2010<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p class=\" eplus-wrapper\">EL s\u00e1bado pas\u00e9 la ma\u00f1ana ordenando armarios. Decid\u00ed definitivamente guardar la ropa de verano y entretiempo para darle prioridad a la de invierno. Eso obliga a cambiar cosas en baldas, perchas y cajones. Exige hacer sitio, vaciar cajas, sacar unas cosas, meter otras. Aparecen ternos que ni te acordabas que exist\u00edan. Se amontonan camisas, pantalones, chaquetas, zapatos, gorras, bufandas, ropa interior, calcetines y corbatas, que ahora me ha dado por salir con ellas en el programa de la tele.<\/p>\n\n\n\n<!--more-->\n\n\n\n<p class=\" eplus-wrapper\">Cuando el zafarrancho es monumental, te preguntas por qu\u00e9 narices has organizado tal fregado. Finalmente, tiras por la calle del medio y lo que iba para gran revoluci\u00f3n se queda en peque\u00f1a algarada.<\/p>\n\n\n\n<p class=\" eplus-wrapper\">Despu\u00e9s de haberme zampado un doble Almer\u00eda-Alicante hace un par de semanas, este viaje a Gij\u00f3n pudiera calificarse como cuento de ni\u00f1os, pero entre la lluvia, el fr\u00edo, las carreteras sin terminar de ser autov\u00edas y la propia tensi\u00f3n de cada jornada, no fue f\u00e1cil la llegada a El Molin\u00f3n. No es un campo que me apasione, porque al margen de aquel d\u00eda en que chut\u00f3 Jes\u00fas Mari Zamora, los recuerdos recientes no son tan agradables.<\/p>\n\n\n\n<p class=\" eplus-wrapper\">De hecho, la \u00faltima vez perdimos (1-0) con arbitraje poco generoso con nosotros del madrile\u00f1o Del Cerro Grande. El cuadro gijon\u00e9s subi\u00f3 aquella temporada, justo cuando nos descoyuntamos en la aciaga tarde de Mendizorroza. Han pasado dos a\u00f1os y unos meses. Entonces presid\u00eda Badiola, entrenaba Eizmendi y solo repitieron ayer como titulares: Carlos Mart\u00ednez, Ansotegi y&nbsp;Mikel Gonz\u00e1lez. \u00a1El f\u00fatbol devora!<\/p>\n\n\n\n<p class=\" eplus-wrapper\">La mareona realista no fue como la de otras ocasiones. \u00bfLa crisis?, \u00bfel derbi que viene?, \u00bfel puente con viaje al Nou Camp?, \u00bfNavidades?&#8230; \u00a1Vaya usted a saber! Pese a todo, llegaron valientes que no quisieron que su equipo quedara desasistido de apoyo. Hubo sitios libres en los restaurantes, sobre todo en ese que tanto me gusta. Estaba el d\u00eda para fabes con almejas. No es lo recomendable cuando vas a trabajar encerrado en una cabina, pero sarna con gusto no pica. As\u00ed que para empezar, chorizos a la sidra y luego el puchero, a discreci\u00f3n, con el cazo buscando y buscando hasta no dejar ni el olor. \u00a1Qu\u00e9 rico, I\u00f1aki!<\/p>\n\n\n\n<p class=\" eplus-wrapper\">Cuando en Asturias cae sirimiri dicen que est\u00e1 &#8220;orbayando&#8221;. Pero ayer a la hora del partido, como si fuera una premonici\u00f3n, sali\u00f3 el sol. Lasarte hab\u00eda previsto una alineaci\u00f3n para la previsible guerra, sobre todo si el campo se pon\u00eda imposible, pero al final salieron los esperados porque al uruguayo los \u00fanicos cambios que le gustan son los de las cajeras cuando va al s\u00faper. No s\u00e9 lo que pens\u00f3 cuando a los dos minutos Gregory nos enchufaba un caracol.<\/p>\n\n\n\n<p class=\" eplus-wrapper\">Sin embargo, por primera vez en lo que va de campeonato, los realistas reaccionaron y remontaron con sendos goles de bella factura. Xabi Prieto, Zurutuza y Aranburu dise\u00f1aron tres remates de fotograf\u00eda para garantizar tres valiosos puntos en la v\u00edspera de ese derbi que tanto a\u00f1ora la feligres\u00eda de este beaterio.&nbsp; Los realistas cogieron esta vez el cazo y buscaron y buscaron en fondo del puchero hasta llevarse la mejor tajada.<\/p>\n\n\n\n<p class=\" eplus-wrapper\">Apunte final: Celebro que a Xabi Alonso le hayan concedido el Tambor de Oro. Creo honestamente que se lo merece, sin que ello vaya en detrimento de los m\u00e9ritos del resto de aspirantes.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sporting de Gij\u00f3n 1-3 Real Sociedad Jornada 13 &#8211; 28\/11\/2010 EL s\u00e1bado pas\u00e9 la ma\u00f1ana ordenando armarios. Decid\u00ed definitivamente guardar la ropa de verano y entretiempo para darle prioridad a la de invierno. Eso obliga a cambiar cosas en baldas, perchas y cajones. Exige hacer sitio, vaciar cajas, sacar unas cosas, meter otras. Aparecen ternos [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":8528,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"editor_plus_copied_stylings":"{}","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[37],"tags":[],"class_list":["post-143","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-beaterios-2010-2011"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/elbeaterio.es\/index.php\/wp-json\/wp\/v2\/posts\/143","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elbeaterio.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elbeaterio.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elbeaterio.es\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/elbeaterio.es\/index.php\/wp-json\/wp\/v2\/comments?post=143"}],"version-history":[{"count":2,"href":"https:\/\/elbeaterio.es\/index.php\/wp-json\/wp\/v2\/posts\/143\/revisions"}],"predecessor-version":[{"id":8553,"href":"https:\/\/elbeaterio.es\/index.php\/wp-json\/wp\/v2\/posts\/143\/revisions\/8553"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elbeaterio.es\/index.php\/wp-json\/wp\/v2\/media\/8528"}],"wp:attachment":[{"href":"https:\/\/elbeaterio.es\/index.php\/wp-json\/wp\/v2\/media?parent=143"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elbeaterio.es\/index.php\/wp-json\/wp\/v2\/categories?post=143"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elbeaterio.es\/index.php\/wp-json\/wp\/v2\/tags?post=143"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}