{"id":3865,"date":"2009-03-01T08:58:53","date_gmt":"2009-03-01T08:58:53","guid":{"rendered":"http:\/\/localhost\/joomla\/2009\/03\/01\/el-humo-por-los-tinteros-de-porcelana-blanca\/"},"modified":"2025-05-30T13:28:01","modified_gmt":"2025-05-30T11:28:01","slug":"el-humo-por-los-tinteros-de-porcelana-blanca","status":"publish","type":"post","link":"https:\/\/elbeaterio.es\/index.php\/2009\/03\/01\/el-humo-por-los-tinteros-de-porcelana-blanca\/","title":{"rendered":"El humo por los tinteros de porcelana blanca&#8230;"},"content":{"rendered":"\n<figure class=\" wp-block-table eplus-wrapper\"><table><thead><tr><th class=\"has-text-align-center\" data-align=\"center\">Deportivo Alav\u00e9s 2-1 Real Sociedad<\/th><\/tr><\/thead><tbody><tr><td class=\"has-text-align-center\" data-align=\"center\">Jornada 26 Liga 2\u00aa &#8211; 28\/02\/2009<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p class=\" eplus-wrapper\">Anoche mientras volv\u00eda de Mendizorroza, con cara de gilipollas, me acord\u00e9 de &#8220;El Patato&#8221;, un religioso que atend\u00eda por Teodosio Luis. Lo hab\u00eda sido todo en su congregaci\u00f3n, pero la edad no perdona y de los \u00f3rganos de decisi\u00f3n pas\u00f3 paulatinamente a la reserva, primero nombr\u00e1ndole pro-director, que era lo mismo que nada y luego destin\u00e1ndole a &#8220;4\u00baR&#8221;, el aula en que militaban los alumnos suspendidos en la rev\u00e1lida de cuarto de bachillerato.<\/p>\n\n\n\n<!--more-->\n\n\n\n<p class=\" eplus-wrapper\">Lo m\u00e1s granado se congregaba en aquella clase con asientos de madera y tinteros de porcelana blanca. Han pasado cuarenta a\u00f1os, pero son inolvidables algunos de los chicos. &#8220;El Pir\u00f3mano&#8221; Miralles viv\u00eda para putear. Su mejor idea era demon\u00edaca. En mitad de una clase de literatura, por el hueco vac\u00edo del tintero, un d\u00eda sali\u00f3 humo de un fuego que prendi\u00f3 dentro del pupitre. &#8220;El Patato&#8221;, con 75 a\u00f1os a cuestas y con problemas para dominar su esf\u00ednter anal, sali\u00f3 despavorido para no volver m\u00e1s. Aquel grupo necesitaba cintura, un fajador que les pusiera las pilas.<\/p>\n\n\n\n<p class=\" eplus-wrapper\">La mayor\u00eda terminaron siendo expulsados y hoy es el d\u00eda en que ignoro cu\u00e1l haya podido ser su destino. La uni\u00f3n forj\u00f3 su fuerza. No pasaban de la decena, pero entre ellos hab\u00eda tal empat\u00eda que era imposible romper su buena relaci\u00f3n. Salvando las distancias, aqu\u00ed el pir\u00f3mano es Lillo. Incendia a su manera. Sus comparecencias siguen siendo un ejercicio de imaginaci\u00f3n portentosa. Ves un partido, sabes el resultado final y te haces una composici\u00f3n del lugar. Luego le escuchas y te niega la mayor. Defiende a los suyos, les protege y les anima a seguir. As\u00ed fue hace una semana, despu\u00e9s del 1-2. As\u00ed fue el jueves, cuando se sent\u00f3 ante micros y plumas. Y ayer, no s\u00e9 ni como fue porque no me quedaban ganas ni de oir..<\/p>\n\n\n\n<p class=\" eplus-wrapper\">Vine a Vitoria, sin quitarme de encima los malos recuerdos. En este campo siempre nos pas\u00f3 algo. Perder para que se salvaran. Perder para que nos fu\u00e9ramos a la mierda, sin olvidarnos de las declaraciones de un entrenador que se atrevi\u00f3 a juzgar el cese de Clemente. \u00a1Ay, cu\u00e1nta traici\u00f3n!. Y para concluir, el remache del a\u00f1o pasado, el martillazo en las ilusiones y la vuelta al principio del camino que ahora recorremos. Pero quedaba m\u00e1s.<\/p>\n\n\n\n<p class=\" eplus-wrapper\">Este equipo ha jugado bien al f\u00fatbol, ha llegado con criterio, ha defendido con tes\u00f3n, ha impuesto su ley a los rivales, ha ofrecido buenas vibraciones. Todo en pasado. Ayer se adelant\u00f3 en una buena jugada ante un rival timorato y no sobrado de recursos. El segundo tiempo era para matar el partido y sentenciar con un resultado indiscutible, pero nos dedicamos a templar la gaita del reloj dejando pasar los minutos. En el tramo final de los partidos nos desprotegemos y primero por la derecha, y luego por la izquierda, en sendos cabezazos, nos mandan al extrarradio de los puestos de ascenso. Que nos hace falta reaccionar lo sabe todo el mundo. Damos pena.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Deportivo Alav\u00e9s 2-1 Real Sociedad Jornada 26 Liga 2\u00aa &#8211; 28\/02\/2009 Anoche mientras volv\u00eda de Mendizorroza, con cara de gilipollas, me acord\u00e9 de &#8220;El Patato&#8221;, un religioso que atend\u00eda por Teodosio Luis. Lo hab\u00eda sido todo en su congregaci\u00f3n, pero la edad no perdona y de los \u00f3rganos de decisi\u00f3n pas\u00f3 paulatinamente a la reserva, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":8641,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"editor_plus_copied_stylings":"{}","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[35],"tags":[],"class_list":["post-3865","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-beaterios-2008-2009"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/elbeaterio.es\/index.php\/wp-json\/wp\/v2\/posts\/3865","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elbeaterio.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elbeaterio.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elbeaterio.es\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/elbeaterio.es\/index.php\/wp-json\/wp\/v2\/comments?post=3865"}],"version-history":[{"count":2,"href":"https:\/\/elbeaterio.es\/index.php\/wp-json\/wp\/v2\/posts\/3865\/revisions"}],"predecessor-version":[{"id":8705,"href":"https:\/\/elbeaterio.es\/index.php\/wp-json\/wp\/v2\/posts\/3865\/revisions\/8705"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elbeaterio.es\/index.php\/wp-json\/wp\/v2\/media\/8641"}],"wp:attachment":[{"href":"https:\/\/elbeaterio.es\/index.php\/wp-json\/wp\/v2\/media?parent=3865"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elbeaterio.es\/index.php\/wp-json\/wp\/v2\/categories?post=3865"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elbeaterio.es\/index.php\/wp-json\/wp\/v2\/tags?post=3865"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}