{"id":4002,"date":"2008-10-22T19:29:08","date_gmt":"2008-10-22T19:29:08","guid":{"rendered":"http:\/\/localhost\/joomla\/2008\/10\/22\/tour-el-mont-ventoux-dictara-sentencia\/"},"modified":"2023-07-02T15:50:17","modified_gmt":"2023-07-02T13:50:17","slug":"tour-el-mont-ventoux-dictara-sentencia","status":"publish","type":"post","link":"https:\/\/elbeaterio.es\/index.php\/2008\/10\/22\/tour-el-mont-ventoux-dictara-sentencia\/","title":{"rendered":"TOUR: El Mont Ventoux dictar\u00e1 sentencia"},"content":{"rendered":"<p>La pen&uacute;ltima etapa del Tour 2009 concluir&aacute; en el Mont Ventoux. Esa circunstancia convierte en decisiva la jornada a la que acceder&aacute;n los ciclistas ciertamente cansados, despu&eacute;s de llevar en sus piernas todas las jornadas precedentes, inclu&iacute;da una contrarreloj individual pocas horas antes de esa subida a uno de los m&iacute;ticos puertos de la ronda gala que se ha presentado en Par&iacute;s.<br \/>\n<!--more--><br \/>\nEn el acto de presentaci&oacute;n se han despejado algunas inc&oacute;gnitas. No acudi&oacute; Lance Armstrong pero s&iacute; Contador lo que quiere decir que Astan&aacute; ser&aacute; de la partida, como la mayor&iacute;a de los equipos franceses de &eacute;lite. Tambi&eacute;n, Euskaltel Euskadi con el renovado Samuel S&aacute;nchez y el guipuzcoano Mikel Astarloza, cuya valoraci&oacute;n respecto al trazado de la prueba ha sido positiva. &quot;Me viene bien&quot;. Una de las novedades corresponde a la desaparici&oacute;n de las bonificaciones. <\/p>\n<p>\nTambi&eacute;n el Tour saldr&aacute; de M&oacute;naco, llegar&aacute; a Suiza, pasando antes por Barcelona. Los Pirineos pierden protagonismo en la zona tradicional con una &uacute;nica etapa que concluir&aacute; en Tarbes, despu&eacute;s de ascender &quot;s&oacute;lo&quot; Aspin y Tourmalet. La organizaci&oacute;n decide apostar los dos d&iacute;as anteriores por las altas cumbres de Andorra-Arcalis y Saint Girons.\n<\/p>\n<p>\nEl Tour 2009 arrancar&aacute; el 4 de julio con una contrarreloj de 15 kil&oacute;metros con salida y llegada en el territorio de los Grimaldi, y concluir&aacute; el 26 de julio con la vig&eacute;sima primera etapa, Montereau -Fault-Yonne &#8211; Par&iacute;s\/Campos El&iacute;seos, de 160, para completar un total de 3.445 kil&oacute;metros.<\/p>\n<p>Frente a los pasados Tour, en el que una contrarreloj se hab&iacute;a convertido en el tradicional juez final de la carrera, la edici&oacute;n de 2009 apuesta como &uacute;ltima gran dificultad por un puerto m&iacute;tico de cuya dureza testimonia que en sus rampas falleci&oacute; en 1967 el brit&aacute;nico Tom Simpson. A la vista de las etapas y sus contenidos, los corredores se han manifestado:\n<\/p>\n<p>\n<em><u>Alberto Contador:<\/u><\/em> &quot;&Eacute;sa es la clave, aprovecharlos, como sucedi&oacute; en la Vuelta a Espa&ntilde;a, en la que las etapas de Andorra no tuvieron demasiada dureza. Espero que este recorrido me venga bien, espero tener buenas piernas y adaptarme al recorrido, porque el Tour siempre lo gana el m&aacute;s fuerte y siempre es una carrera dura. Quiero aprovechar la oportunidad&quot;.\n<\/p>\n<p>\n<em><u>Carlos Sastre:<\/u><\/em> &quot;A nivel particular creo que es un recorrido que me favorece, porque siguiendo la t&oacute;nica de este a&ntilde;o presenta poca contrarreloj, creo que son en total 55 kil&oacute;metros m&aacute;s la crono por equipos, por lo tanto es un aliciente para cualquier escalador como yo, puesto que no somos grandes especialistas en cuanto al crono. Y uno creo que este a&ntilde;o, como dec&iacute;a al comienzo creo que es especial por muchas cosas, pero sobre todo por esa incertidumbre que ha despertado ese cambio de la &uacute;ltima contrarreloj por una etapa de monta&ntilde;a, que puede deparar alguna sorpresa significativa en la resoluci&oacute;n de este Tour de Francia&quot;.\n<\/p>\n<p>\n<em><u>Samuel S&aacute;nchez:<\/u><\/em> &quot;Los organizadores buscan la emoci&oacute;n y el espect&aacute;culo y creo que lo van a lograr. Puede haber un cambio de l&iacute;der en la crono de Annecy y al d&iacute;a siguiente otro cambio en el Ventoux. Habr&aacute; emoci&oacute;n, que es lo que buscan y que el p&uacute;blico se divierta. Tengo que conocer muchos puertos, no puedo hacer una valoraci&oacute;n. Pero es un Tour duro, la &uacute;ltima semana es para fondistas puros, se funden los Alpes y la crono. Todav&iacute;a no s&eacute; como voy a enfocar la temporada. Acabo de terminar este a&ntilde;o y no he pensado en el que viene. Ahora quiero descansar, estar tranquilo, algo que no he logrado desde que gan&eacute; los Juegos de Pek&iacute;n&quot;,<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La pen&uacute;ltima etapa del Tour 2009 concluir&aacute; en el Mont Ventoux. Esa circunstancia convierte en decisiva la jornada a la que acceder&aacute;n los ciclistas ciertamente cansados, despu&eacute;s de llevar en sus piernas todas las jornadas precedentes, inclu&iacute;da una contrarreloj individual pocas horas antes de esa subida a uno de los m&iacute;ticos puertos de la ronda [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"editor_plus_copied_stylings":"{}","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[41],"tags":[],"class_list":["post-4002","post","type-post","status-publish","format-standard","hentry","category-comentarios-2008-2009"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/elbeaterio.es\/index.php\/wp-json\/wp\/v2\/posts\/4002","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elbeaterio.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elbeaterio.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elbeaterio.es\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/elbeaterio.es\/index.php\/wp-json\/wp\/v2\/comments?post=4002"}],"version-history":[{"count":1,"href":"https:\/\/elbeaterio.es\/index.php\/wp-json\/wp\/v2\/posts\/4002\/revisions"}],"predecessor-version":[{"id":6140,"href":"https:\/\/elbeaterio.es\/index.php\/wp-json\/wp\/v2\/posts\/4002\/revisions\/6140"}],"wp:attachment":[{"href":"https:\/\/elbeaterio.es\/index.php\/wp-json\/wp\/v2\/media?parent=4002"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elbeaterio.es\/index.php\/wp-json\/wp\/v2\/categories?post=4002"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elbeaterio.es\/index.php\/wp-json\/wp\/v2\/tags?post=4002"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}