{"id":449,"date":"2021-10-29T16:13:00","date_gmt":"2021-10-29T16:13:00","guid":{"rendered":"https:\/\/elbeaterio.es\/?p=449"},"modified":"2025-05-30T17:40:40","modified_gmt":"2025-05-30T15:40:40","slug":"mikel-merino-quiero-tu-camiseta","status":"publish","type":"post","link":"https:\/\/elbeaterio.es\/index.php\/2021\/10\/29\/mikel-merino-quiero-tu-camiseta\/","title":{"rendered":"\u00a1Mikel (Merino) quiero tu camiseta!"},"content":{"rendered":"\n<figure class=\" wp-block-table eplus-wrapper\"><table><thead><tr><th class=\"has-text-align-center\" data-align=\"center\">Celta de Vigo 0-2 Real Sociedad<\/th><\/tr><\/thead><tbody><tr><td class=\"has-text-align-center\" data-align=\"center\">Jornada 11 Liga &#8211; 28\/10\/2021<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p class=\" eplus-wrapper\">Hace unas semanas solicitaba, tambi\u00e9n desde aqu\u00ed, una camiseta. Era a Mikel Oyarzabal despu\u00e9s de uno de esos partidos en los que el personal, si lo usara, deber\u00eda quitarse el sombrero y rendirse al virtuosismo. Como no he recibido respuesta, lo intento con otra debilidad. No es que pierda la esperanza y abandone al \u201c10\u201d, pero pruebo con el \u201c8\u201d que ha vuelto a demostrar su clase dentro y fuera del terreno de juego. Cuando despu\u00e9s del match del Metropolitano debi\u00f3 salir a la palestra para manifestarse sobre la jugada de marras, aquella en la que hemos sentido que nos tangaron. Se explic\u00f3 divino de la muerte. Dej\u00f3 las cosas claras, sin una mala palabra ni un mal gesto por la decisi\u00f3n de los colegiados, el de arriba y el de abajo. Se le notaba el disgusto en la cara por ser, indirectamente, culpable del penalti que desemboc\u00f3 en el resultado final. El se\u00f1or conde ha dado tanto a este equipo que no cabe un solo reproche que hacerle. M\u00e1xime cuando sobre la decisi\u00f3n del \u00e1rbitro se han vertido litros de tinta en comentarios escritos y cataratas de palabras en las tertulias de aqu\u00ed y de all\u00e1 con nula unanimidad. Cuando hay tanta diversidad al respecto, matarile\u2026<\/p>\n\n\n\n<p class=\" eplus-wrapper\">El d\u00eda en que renov\u00f3 su contrato hasta 2025 dej\u00f3 una frase que no se olvida con facilidad: \u201cDonde eres feliz, quieres estar\u201d Esas cosas que parecen nimias las valoro cada vez m\u00e1s. El d\u00eda que compart\u00ed con \u00e9l una hora de radio, en una entrevista muy personal, ya me pareci\u00f3 que no era un futbolista al uso, que las palabras transmit\u00edan realidades que hab\u00eda vivido, muy distintas a las actuales en las que se mueve entre la medalla ol\u00edmpica, los compromisos de la selecci\u00f3n y el d\u00eda a d\u00eda de su equipo en el que es un referente, un santo y se\u00f1a de entrega y compromiso. Ayer el remate que origina el segundo tanto es de \u00e9l. \u00a1Mikel, quiero tu camiseta!<\/p>\n\n\n\n<p class=\" eplus-wrapper\">El de anoche no era un partido f\u00e1cil para \u00e9l, porque alg\u00fan vestigio ol\u00edvico anida en su intimidad. Miguel su padre, defendi\u00f3 la camiseta del Celta de Vigo durante tres temporadas y un recuerdo lejano seguro que palpita en su coraz\u00f3n aunque sea por historias que le han contado en el camino. Y no lo era tampoco, porque el rival se mostr\u00f3 tal y como le gusta a su entrenador. Les vi jugar el lunes en Getafe y me gustaron. M\u00e1s all\u00e1 de las facilidades ofrecidas por el oponente que se mostr\u00f3 inerme, supieron aprovechar su calidad y las oportunidades que fueron capaces de crear. Intu\u00ed que anoche nos \u00edbamos a encontrar de frente con un rival inc\u00f3modo. Tocaba bregar de lo lindo.<\/p>\n\n\n\n<p class=\" eplus-wrapper\">Era vital que el nivel de concentraci\u00f3n fuera m\u00e1ximo, como si no hubiera un ma\u00f1ana (que lo hay dentro de dos d\u00edas) y que la gente pensara s\u00f3lo en lo que estaba afrontando desde que Melero L\u00f3pez peg\u00f3 el pitido de arranque. \u00bfQu\u00e9 pasa por la cabeza del m\u00edster? Lo sabe \u00e9l y sus cercanos. Para empezar, Ryan bajo palos (se gan\u00f3 el suelo a pulso). Repiti\u00f3 el mismo plan que cuando debut\u00f3. Compiti\u00f3 en la estaci\u00f3n intermedia del grupo de tres de aquella semana. Se estren\u00f3 en Granada, despu\u00e9s de empatar en casa ante el Sevilla y antes de ganar al Elche en Anoeta. Ayer volvi\u00f3 a ser titular en el segundo compromiso de otra semana con tres citas y brill\u00f3 con luz propia en unas cuantas acciones decisivas del primer tiempo. Llegar al descanso con empate sin goles rozaba el milagro. El resto de los titulares elegidos por Imanol no dejaba lugar a dudas. Casi, casi, la cr\u00e8me de la cr\u00e8me. Ni se guard\u00f3 nada en el tintero (tampoco el Celta), ni cosa parecida. \u00a1Eso son bemoles! Porque no usa camiseta con n\u00famero en el banquillo que, si no, le ped\u00eda tambi\u00e9n la suya. Volvi\u00f3 al 4-3-3. Retornaron Zubimendi, despu\u00e9s de la<\/p>\n\n\n\n<p class=\" eplus-wrapper\">lesi\u00f3n; Aihen, tras la sanci\u00f3n y dos extremos como Portu y Januzaj, dejando a Gorosabel, Zubeldia, Guevara y Sorloth, titulares el pasado domingo, en zona de banquillos.<\/p>\n\n\n\n<p class=\" eplus-wrapper\">Ah\u00ed y en el resto del estadio se empaparon de agua. Aparecieron el viento y la lluvia con ganas de quedarse y los equipos se encontraron en un ambiente desapacible, que no ayud\u00f3 mucho al buen juego, pese al delirante inicio de los gallegos que en cinco minutos atacaron sin desmayo. Dio la sensaci\u00f3n de que a la Real le cost\u00f3 entrar en el partido. La tremenda presi\u00f3n de los c\u00e9lticos no les dej\u00f3 desplegar el juego y llevar peligro a la meta de Dituro. Se pod\u00eda pensar que la exhibici\u00f3n de poder\u00edo y fortaleza de los vigueses no pod\u00eda durar mucho tiempo, porque el desgaste es colosal. Lo sab\u00eda la Real que, si lleg\u00f3 al descanso sin sufrir menoscabo, era consciente de que en el segundo tiempo alguna oportunidad iba a aparecer. \u00a1Y apareci\u00f3!<\/p>\n\n\n\n<p class=\" eplus-wrapper\">Cerca de la hora de juego, el equipo saca enorme r\u00e9dito a un contraataque espl\u00e9ndido, como en Madrid hace unos d\u00edas. Lo termin\u00f3 Isak, despu\u00e9s de una jugada de libro que pudo irse al traste porque el asistente del \u00e1rbitro levant\u00f3 el bander\u00edn de modo inexplicable. El VAR le desautoriz\u00f3 porque no hab\u00eda ni duda y el tanto subi\u00f3 al marcador. El Celta se encontr\u00f3 entonces con lo que no esperaba. Cuesta arriba y con cambio de sistema defensivo en el oponente que le complic\u00f3 mucho las cosas. La zaga estuvo enorme y fue minando cada vez m\u00e1s las ganas del conjunto gallego por revertir la situaci\u00f3n.<\/p>\n\n\n\n<p class=\" eplus-wrapper\">Misi\u00f3n imposible despu\u00e9s de encajar un segundo tanto, a bal\u00f3n parado. Be\u00f1at Turrientes pone un caramelo en la zona de remate. Entran Merino y Elustondo. Para unos, comenzando por la televisi\u00f3n que transmite, el gol es del navarro. Para otros, de Aritz que es el \u00faltimo al que le pega el bal\u00f3n en la espalda antes de colarse en la porter\u00eda. Fue el momento del Abrazo de Beasain, dos jugadores del pueblo, con vidas paralelas, con duras experiencias de vida, formados en la misma cantera. No son como en Bergara, ni Espartero, ni Maroto, pero s\u00ed generales con alma txuriurdin. Por fas o por nefas, txitxarro a la cazuela y tres puntos m\u00e1s que sientan muy bien por lo mucho que cuesta conseguirlos. Ver al equipo en el primer puesto de la tabla, aunque no quieren o\u00edr hablar de ello, premia el esfuerzo y el compromiso con el proyecto y la camiseta que defienden. \u00a1Quiero la de Merino!<\/p>\n\n\n\n<p class=\" has-gridlove-highlight-acc-background-color has-background eplus-wrapper\">Apunte con brillantina: Tenemos gemelos para rato. Ayer se conoci\u00f3 que Ronaldo y su amada Georgina van a ser padres de una pareja de ni\u00f1os, tal y como se ense\u00f1a en la ecograf\u00eda compartida. No s\u00e9 con qu\u00e9 nos dar\u00e1n m\u00e1s tabarra. Si con esto, o con el Bar\u00e7a. Jugar, lo que se dice jugar, los catalanes no juegan mucho. Ganar, lo que se dice ganar, no ganan mucho. Pero entretener\u2026<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Celta de Vigo 0-2 Real Sociedad Jornada 11 Liga &#8211; 28\/10\/2021 Hace unas semanas solicitaba, tambi\u00e9n desde aqu\u00ed, una camiseta. Era a Mikel Oyarzabal despu\u00e9s de uno de esos partidos en los que el personal, si lo usara, deber\u00eda quitarse el sombrero y rendirse al virtuosismo. Como no he recibido respuesta, lo intento con otra [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":450,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"editor_plus_copied_stylings":"{}","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[7],"tags":[],"class_list":["post-449","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-beaterios-2021-2022"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/elbeaterio.es\/index.php\/wp-json\/wp\/v2\/posts\/449","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elbeaterio.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elbeaterio.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elbeaterio.es\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/elbeaterio.es\/index.php\/wp-json\/wp\/v2\/comments?post=449"}],"version-history":[{"count":2,"href":"https:\/\/elbeaterio.es\/index.php\/wp-json\/wp\/v2\/posts\/449\/revisions"}],"predecessor-version":[{"id":8919,"href":"https:\/\/elbeaterio.es\/index.php\/wp-json\/wp\/v2\/posts\/449\/revisions\/8919"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elbeaterio.es\/index.php\/wp-json\/wp\/v2\/media\/450"}],"wp:attachment":[{"href":"https:\/\/elbeaterio.es\/index.php\/wp-json\/wp\/v2\/media?parent=449"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elbeaterio.es\/index.php\/wp-json\/wp\/v2\/categories?post=449"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elbeaterio.es\/index.php\/wp-json\/wp\/v2\/tags?post=449"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}