{"id":6968,"date":"2021-02-25T23:42:00","date_gmt":"2021-02-25T21:42:00","guid":{"rendered":"https:\/\/elbeaterio.es\/?p=6968"},"modified":"2025-05-30T16:43:19","modified_gmt":"2025-05-30T14:43:19","slug":"y-si","status":"publish","type":"post","link":"https:\/\/elbeaterio.es\/index.php\/2021\/02\/25\/y-si\/","title":{"rendered":"Y si&#8230;"},"content":{"rendered":"\n<figure class=\" wp-block-table eplus-wrapper\"><table><thead><tr><th class=\"has-text-align-center\" data-align=\"center\">Manchester United 0-0 Real Sociedad<\/th><\/tr><\/thead><tbody><tr><td class=\"has-text-align-center\" data-align=\"center\">Europa League Dieciseisavos (Vuelta) &#8211; 25\/02\/2021<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p class=\" eplus-wrapper\">Cu\u00e1ntas veces en nuestras vidas hemos construido frases e ideas con un &#8220;Y si&#8230;&#8221; por delante? Cuando llegan las fiestas navide\u00f1as, por ejemplo, quien m\u00e1s quien menos lleva un d\u00e9cimo de loter\u00eda. Lo compra en solitario, lo comparte con amigos o juega el mismo n\u00famero que el resto de compa\u00f1eros de la empresa en la que trabaja. &#8220;\u00bfY si nos toca?&#8221;, se preguntan. Entonces se desata la imaginaci\u00f3n y dejan volar los sue\u00f1os creando una particular Arcadia feliz a la que se destinar\u00eda el dinero del premio. Se mueven los bombos, cantan los ni\u00f1os y se termina hablando de salud.<\/p>\n\n\n\n<p class=\" eplus-wrapper\">El partido de anoche llevaba una carga, no demasiado pesada, de ilusiones. Cab\u00eda perfectamente un Y si&#8230; en toda regla. \u00bfOs imagin\u00e1is que les metemos cuatro y les ganamos en la pr\u00f3rroga? No s\u00e9 qu\u00e9 hubiera pasado en este territorio, pero en Manchester le mandan al entrenador a su casa&nbsp;<em>per omnia saecula saeculorum<\/em>. As\u00ed nos evit\u00e1bamos la tentaci\u00f3n de ficharle. No olvidar\u00e9 mientras viva y no me falle la memoria que, despu\u00e9s de aquella monumental expedici\u00f3n de 2013, el t\u00e9cnico rival recal\u00f3 por estos pagos. Hay preguntas en la larga historia del club que no las responde nadie. Esta es una de ellas.<\/p>\n\n\n\n<p class=\" eplus-wrapper\">Aquella cita de octubre movi\u00f3 a muchos aficionados y otros que no lo eran. Dijeron que entre cinco mil y seis mil. Una pasada. Quer\u00edan vivir un d\u00eda apasionante, hist\u00f3rico. El equipo dio la cara en todo momento. Nos metieron un gol en propia meta nada m\u00e1s empezar, pero el grupo lleg\u00f3 entero hasta el pitido final. Cuando el holand\u00e9s Nijhuis hizo sonar el silbato, se habl\u00f3 de pena por la derrota, pero de alegr\u00eda por la dignidad del colectivo y su comportamiento en un campo emblem\u00e1tico. Estos d\u00edas, muchos aficionados han colgado en las redes sociales fotograf\u00edas de aquella experiencia inolvidable. \u00c9sta que termin\u00f3 anoche no pasar\u00e1 a la historia por descafeinada. Antes del partido, Imanol se refiri\u00f3 a la imagen, al compromiso y a los valores del equipo. Era un reto accesible. No le gustan los menoscabos.<\/p>\n\n\n\n<p class=\" eplus-wrapper\">Muchas veces navego en p\u00e1ginas de internet para seguir la recomendaci\u00f3n de los lugares que merece la pena visitar de esas ciudades a las que toca desplazarse. Os sugiero, si no lo hab\u00e9is hecho, que escrib\u00e1is Manchester en el buscador y encontrareis que la estaci\u00f3n del tren y el estadio de f\u00fatbol de nuestros contrarios anoche ocupan lugares principales en la escala de valores. Ni sigo, ni hago comentarios no vaya a ser que el alcalde de aquella ciudad me invite a pasar unos d\u00edas para que cambie de opini\u00f3n. Aunque debo reconocer tambi\u00e9n que, en una pretemporada por tierras de Escocia, llegamos a Glasgow. Ciudad con fama de horrorosa. Llevaba la idea de una urbe fe\u00edsima. Nada m\u00e1s lejos de la realidad, porque descubr\u00ed muchos sitios que merec\u00edan la pena, jardines petados de hermosas flores y lugares cautivadores. Entre ellos un espectacular restaurante Art Deco en el que no cenamos mal, hecho casi milagroso en ese pa\u00eds.<\/p>\n\n\n\n<p class=\" eplus-wrapper\">Tengo muy clarinete que soy del City y que si viviera all\u00ed, vestir\u00eda de celeste y que pagar\u00eda unas cuantas libras por ver jugar a De Bruyne que, os lo he contado alguna vez, me parece un futbolista apasionante. Como me gusta el buen f\u00fatbol, disipar\u00eda en poco tiempo todas las dudas. El lunes comet\u00ed un error de principiante. No se me ocurri\u00f3 nada mejor que tragarme entero un ManU-Newcastle, poco sugerente. Les miro con lupa. Cuentan con buenos futbolistas, pero&#8230; Pegada s\u00ed, suficiente para ganar. Las urracas sobrevolaban el c\u00e9sped y tardaron media hora en encajar un gol. Es cierto que el remate de Rashford, que abri\u00f3 el tanteo, fue un golazo. Por si fuera poca la raci\u00f3n, ayer repitieron el partido por el mismo canal, a eso de la media tarde. Por supuesto, pas\u00e9 de largo. Nunca son recomendables los empachos.<\/p>\n\n\n\n<p class=\" eplus-wrapper\">Si hace un par de a\u00f1os Gorosabel y quien suscribe nos tomamos un caf\u00e9, hablamos de f\u00fatbol y le digo que va a jugar el Old Trafford y que ese d\u00eda le har\u00e1n un penalti, seguro que me miraba raro y pensaba que no estaba en mis cabales. Si a Guevara, Zubimendi o Sagnan les comentas hace pocos meses que ser\u00e1n titulares en un partido como el de ayer no pensar\u00edan diferente. Imaginad lo que pod\u00edan pensar anoche las buenas gentes de Etxauri, viendo a Aihen Mu\u00f1oz defender en un c\u00f3rner a Anthony Martial, siendo protagonista en un partido de semejante envergadura. Se sentir\u00edan muy orgullosos del conciudadano. En las pr\u00f3ximas fiestas de San Antonio deber\u00eda pronunciar el preg\u00f3n y echar el cohete si el virus no se interpone. Esta es una realidad, no virtual precisamente, con la que ratificas punto por punto todo lo que viene sucediendo desde que el club eligi\u00f3 un camino y lo sigue a rajatabla. Apuesta firme por los jugadores que han crecido a tu lado.<\/p>\n\n\n\n<p class=\" eplus-wrapper\">Un d\u00eda decidi\u00f3 fichar a Alex Remiro, quien por cierto se ha cascado una se\u00f1ora eliminatoria. Trajo a Januzaj, a Isak o a Mikel Merino. Dio alas a Zubeldia y puso el brazalete de capit\u00e1n en el brazo izquierdo de Oyarzabal. Se le escap\u00f3 un penalti, quiz\u00e1s por meterlo por un lugar inhabitual a lo que acostumbra. No se merece ese disgusto. Hasta entonces el equipo estaba jugando muy bien, llegando al \u00e1rea inglesa y fabricando jugadas de m\u00e9rito. Luego, a ra\u00edz de la oportunidad perdida, cedi\u00f3 y le cost\u00f3 hasta el descanso mantener esa capacidad de dominar el bal\u00f3n. Entre otras cosas, porque el Manchester reaccion\u00f3 antes de que le empezaran a sonar las orejas.<\/p>\n\n\n\n<p class=\" eplus-wrapper\">La entrada de Barrenetxea, Bautista (al que casi descoyunta Lindel\u00f6f) y Portu, en el inicio del segundo tiempo, reforzaba la tesis de lo que acabo de escribir, al tiempo que respond\u00eda a un plan preconcebido por el t\u00e9cnico. M\u00e1s tarde, el turno fue para Merquelanz y Guridi, quienes junto a Sagnan hace un a\u00f1o vest\u00edan la roja camiseta del Mirand\u00e9s. Procesos de enorme progreso. En ese cap\u00edtulo de decisiones, tampoco le tembl\u00f3 el pulso al entrenador.<\/p>\n\n\n\n<p class=\" eplus-wrapper\">Seguro que entre ceja y ceja est\u00e1 instalado el partido del lunes en Valdebebas. Ese ser\u00e1 otro cantar. A la falta de fortuna en el penalti, le acompa\u00f1\u00f3 el remate de Sagnan al larguero. Nos vamos de Europa sin haber perdido un solo encuentro lejos de casa. La \u00fanica pena es no haber ganado a los ingleses en su campo. \u00bfY si el penalti hubiera entrado? Pues eso, salida por la puerta grande. Un apunte final. Me gust\u00f3 el arbitraje del belga Visser y la valent\u00eda del holand\u00e9s Blom desde el v\u00eddeo arbitraje para anular el gol de los locales, tras el tarantant\u00e1n a Jon Bautista, al que hoy le deben doler hasta las pesta\u00f1as. En todas partes no cuecen las mismas habas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Manchester United 0-0 Real Sociedad Europa League Dieciseisavos (Vuelta) &#8211; 25\/02\/2021 Cu\u00e1ntas veces en nuestras vidas hemos construido frases e ideas con un &#8220;Y si&#8230;&#8221; por delante? Cuando llegan las fiestas navide\u00f1as, por ejemplo, quien m\u00e1s quien menos lleva un d\u00e9cimo de loter\u00eda. Lo compra en solitario, lo comparte con amigos o juega el mismo [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":6969,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"editor_plus_copied_stylings":"{}","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[53],"tags":[],"class_list":["post-6968","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-el-beaterio-2020-2021"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/elbeaterio.es\/index.php\/wp-json\/wp\/v2\/posts\/6968","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elbeaterio.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elbeaterio.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elbeaterio.es\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/elbeaterio.es\/index.php\/wp-json\/wp\/v2\/comments?post=6968"}],"version-history":[{"count":2,"href":"https:\/\/elbeaterio.es\/index.php\/wp-json\/wp\/v2\/posts\/6968\/revisions"}],"predecessor-version":[{"id":8868,"href":"https:\/\/elbeaterio.es\/index.php\/wp-json\/wp\/v2\/posts\/6968\/revisions\/8868"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elbeaterio.es\/index.php\/wp-json\/wp\/v2\/media\/6969"}],"wp:attachment":[{"href":"https:\/\/elbeaterio.es\/index.php\/wp-json\/wp\/v2\/media?parent=6968"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elbeaterio.es\/index.php\/wp-json\/wp\/v2\/categories?post=6968"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elbeaterio.es\/index.php\/wp-json\/wp\/v2\/tags?post=6968"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}