{"id":7978,"date":"2014-08-25T00:00:00","date_gmt":"2014-08-24T22:00:00","guid":{"rendered":"https:\/\/elbeaterio.es\/index.php\/2014\/08\/25\/la-cubeta-de-hielo\/"},"modified":"2025-05-27T19:27:09","modified_gmt":"2025-05-27T17:27:09","slug":"la-cubeta-de-hielo","status":"publish","type":"post","link":"https:\/\/elbeaterio.es\/index.php\/2014\/08\/25\/la-cubeta-de-hielo\/","title":{"rendered":"La cubeta de hielo"},"content":{"rendered":"\n<p class=\" eplus-wrapper\">SD Eibar 1 &#8211; Real Sociedad 0 (Jornada 1 &#8211; 24\/08\/2014)<\/p>\n\n\n\n<p class=\" eplus-wrapper\">Resulta que la Real afront\u00f3 la cita de ayer en Ipurua con varios apuntes, cuando menos, llamativos. Lleg\u00f3 a Eibar despu\u00e9s de haber ganado tres partidos oficiales consecutivos en un inicio de campa\u00f1a. Esto no suced\u00eda desde 1963, a\u00f1o en el que muchos de vosotros no hab\u00edais nacido y otros and\u00e1bamos chupando piruletas. Est\u00e1bamos en Segunda y los triunfos fueron a costa del Alav\u00e9s (1-0), Orense (0-2) y Celta (2-0). Lo le\u00ed en una informaci\u00f3n que publicaba Pedro Mart\u00edn el d\u00eda del Krasnodar.<\/p>\n\n\n\n<p class=\" eplus-wrapper\">Horas m\u00e1s tarde, otro seguidor de redes sociales se fijaba en los goles de Xabi Prieto. Desde antes de las pasadas navidades no marcaba un tanto. Ahora lleva tres, uno m\u00e1s que en toda la temporada pasada en la que, por lo visto, no se las met\u00eda ni al arco iris. Rachas y realidades que comparto contigo para ofrecer temas de diversidad de los que hablar y comentar en tertulias, barras de cafeter\u00eda o puestos de trabajo, ahora que poco a poco todo vuelve a su ser.<\/p>\n\n\n\n<p class=\" eplus-wrapper\">A la par de estas cosas, otras m\u00e1s habituales que se refieren a la ubicaci\u00f3n de Elustondo como central, al cambio de sistema con forma de rombo y al quilombo permanente en torno al entrenador. Gusta y no gusta, como los helados de morcilla. Volv\u00eda a una de sus casas predilectas. All\u00ed se hinch\u00f3 a meter goles y a experimentar. Sabe de sobra c\u00f3mo es la casa y sab\u00eda de sobra lo que se iba a encontrar. Supongo que a la hora de disponer el equipo de partida, no pens\u00f3 ni en el jueves, ni en el domingo pr\u00f3ximo, en donde le esperan sendos marrones de aupa. Quer\u00eda empezar la Liga ganando.<\/p>\n\n\n\n<p class=\" eplus-wrapper\">No disfruto mucho con los derbis provinciales, porque normalmente convives con todos los protagonistas y hay una relaci\u00f3n que sobrepasa el mero nivel informativo. Por eso, porque al final del encuentro unos se muestran felices y los otros decepcionados y nunca sabes muy bien qu\u00e9 cara poner y qu\u00e9 decir, no terminas de sentirte a gusto. Incluso, fr\u00edo.<\/p>\n\n\n\n<p class=\" eplus-wrapper\">Ahora se ha puesto de moda echarse por encima una cubeta de agua helada como modo de ayudar a las personas afectadas por esclerosis lateral amiotr\u00f3fica (ELA). Los medi\u00e1ticos se prestan a grabar un v\u00eddeo, retando a otros amigos o compa\u00f1eros para que sigan sus pasos y colaboren por la causa. Esa es una realidad, pero hay otra tradicional, el famoso jarro de agua fr\u00eda que lo sientes sin que nadie lo vierta por encima de tu cabeza. Estaba claro que ayer iba a caer sobre uno de los dos conjuntos.<\/p>\n\n\n\n<p class=\" eplus-wrapper\">El Eibar so\u00f1aba con un debut en Primera como el que firm\u00f3. Tambi\u00e9n Javi Lara, cuyo gol decidi\u00f3 la contienda. Creo que de modo merecido. Acert\u00f3 a poner el bal\u00f3n donde se debe, aprovechando las facilidades y el desajuste permanente de un equipo que sufri\u00f3 en las acciones a bal\u00f3n parado. El llamado gol psicol\u00f3gico al borde del descanso reforz\u00f3 la conducta de los de Garitano, aumentando moral y convicci\u00f3n.<\/p>\n\n\n\n<p class=\" eplus-wrapper\">La Real que no daba una, ni antes ni despu\u00e9s, no encontr\u00f3 el sitio en ning\u00fan momento. Tampoco la forma de jugar. Patad\u00f3n y tente tieso. Poco bal\u00f3n por abajo, nada de f\u00fatbol y menos remate. Con ese bagaje, poca leche. No s\u00e9 si por la deriva del partido de ida y vuelta ante los rusos, no s\u00e9 si por el espacio del terreno de juego, no s\u00e9 si por exceso de confianza, no s\u00e9 si por falta de tensi\u00f3n, no s\u00e9 si por? se ganaron todos, incluida la banda, un buen balde de agua fr\u00eda. Para espabilar.<\/p>\n\n\n\n<p class=\" eplus-wrapper\">Del mismo modo que los armeros cautivaron a los suyos y celebraron la fiesta, los realistas decepcionaron con todas las de la ley. Al cuadro txuri-urdin le gan\u00f3 un equipo que sali\u00f3 con ocho titulares que hace dos a\u00f1os estaban en Segunda B, que ascendieron hace un a\u00f1o y hace unos meses y que el buen entrenador que les conduce determin\u00f3 premiarles por sus m\u00e9ritos. Ya pueden hablar de su debut en Primera, del primer triunfo, de las emociones. Saben de sobra qu\u00e9 camino deben seguir. Y lo har\u00e1n. Firmar\u00e1n tardes buenas como ante los realistas y encontrar\u00e1n dificultades como las que se prev\u00e9n a orillas del Manzanares la semana que viene.<\/p>\n\n\n\n<p class=\" eplus-wrapper\">Para la Real no encuentro palabras. En Ipurua no se salv\u00f3 ni el que lleva el botijo. Era previsible que pasaran apuros porque el rival aprieta. Esperaba alguna se\u00f1al que nos dijera que aspiraban a ganar y que lo intentaban. Si fue as\u00ed, lo disimularon. Este partido y este resultado aumentar\u00e1n el caudal de voces cr\u00edticas, que las hay. Se esperan respuestas positivas y reacciones que hagan olvidar cuanto antes el chandr\u00edo de ayer. No hay defensa ante semejante dislate.<\/p>\n\n\n\n<p class=\" eplus-wrapper\">Aunque esperaba algo parecido, el balde de agua fr\u00eda llevaba demasiado contenido. Y los aficionados, sobre los que volcaron el barre\u00f1o, no se merecen semejante disgusto.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SD Eibar 1 &#8211; Real Sociedad 0 (Jornada 1 &#8211; 24\/08\/2014) Resulta que la Real afront\u00f3 la cita de ayer en Ipurua con varios apuntes, cuando menos, llamativos. Lleg\u00f3 a Eibar despu\u00e9s de haber ganado tres partidos oficiales consecutivos en un inicio de campa\u00f1a. Esto no suced\u00eda desde 1963, a\u00f1o en el que muchos de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":7844,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"editor_plus_copied_stylings":"{}","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[59],"tags":[],"class_list":["post-7978","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-beaterios-2014-2015"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/elbeaterio.es\/index.php\/wp-json\/wp\/v2\/posts\/7978","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elbeaterio.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elbeaterio.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elbeaterio.es\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/elbeaterio.es\/index.php\/wp-json\/wp\/v2\/comments?post=7978"}],"version-history":[{"count":1,"href":"https:\/\/elbeaterio.es\/index.php\/wp-json\/wp\/v2\/posts\/7978\/revisions"}],"predecessor-version":[{"id":8058,"href":"https:\/\/elbeaterio.es\/index.php\/wp-json\/wp\/v2\/posts\/7978\/revisions\/8058"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elbeaterio.es\/index.php\/wp-json\/wp\/v2\/media\/7844"}],"wp:attachment":[{"href":"https:\/\/elbeaterio.es\/index.php\/wp-json\/wp\/v2\/media?parent=7978"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elbeaterio.es\/index.php\/wp-json\/wp\/v2\/categories?post=7978"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elbeaterio.es\/index.php\/wp-json\/wp\/v2\/tags?post=7978"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}