{"id":7982,"date":"2014-09-22T00:00:00","date_gmt":"2014-09-21T22:00:00","guid":{"rendered":"https:\/\/elbeaterio.es\/index.php\/2014\/09\/22\/que-depresion\/"},"modified":"2025-05-27T19:27:09","modified_gmt":"2025-05-27T17:27:09","slug":"que-depresion","status":"publish","type":"post","link":"https:\/\/elbeaterio.es\/index.php\/2014\/09\/22\/que-depresion\/","title":{"rendered":"\u00a1Qu\u00e9 depresi\u00f3n!"},"content":{"rendered":"\n<p class=\"has-gridlove-meta-color has-text-color has-link-color eplus-wrapper wp-elements-624f53508c46519215f052873f63a591\">Real Sociedad 1 &#8211; UD Almer\u00eda 2 (Jornada 4 &#8211; 21\/09\/2014)<\/p>\n\n\n\n<p class=\" eplus-wrapper\">La vida est\u00e1 llena de contrastes. Existe muchas veces la posibilidad de elegir entre una cosa u otra. Trato de situarte en dos escenarios coincidentes ayer al mediod\u00eda. En el estudio de directo disponemos de dos grandes pantallas de televisi\u00f3n. Gracias a ellas tratamos de conseguir la mejor visi\u00f3n para luego transmitir los partidos en la emisora y sentir cercana la lejan\u00eda. Casi siempre est\u00e1n sintonizados los mismos canales. Ayer, no.<\/p>\n\n\n\n<p class=\" eplus-wrapper\">En la izquierda eleg\u00ed las regatas de traineras, dejando el partido de Anoeta en la otra. El mar y la tierra. El verde esperanza y la desesperanza. El \u00e9xito y el fracaso. La felicidad y la melancol\u00eda. El premio y el castigo. El acierto y la inoperancia. La alegr\u00eda y la tristeza. Entre ambos aparatos existe medio metro de distancia y entre los escenarios unos 100 kil\u00f3metros. Y ya ves, cu\u00e1ntas diferencias y los contrastes de los que te hablaba.<\/p>\n\n\n\n<p class=\" eplus-wrapper\">Lleg\u00f3 un momento que estuve a un tris de abandonar el f\u00fatbol y narrar las emociones de quienes han peleado el \u00e9xito desde noviembre, entrenando horas y horas en los gimnasios y erg\u00f3metros, abrigados en las fr\u00edas aguas del invierno, para conseguir ahora hacer inmensamente dichosos a sus seguidores. Todos los remeros merecen un reconocimiento y los de Hondarribia, m\u00e1s. Miles de renuncias a muchas cosas para llegar enteros al final e intentarlo con todas sus fuerzas. Siete banderas, el t\u00edtulo de liga y el segundo puesto en La Concha. La culminaci\u00f3n del trabajo bien hecho.<\/p>\n\n\n\n<p class=\" eplus-wrapper\">Sent\u00eda envidia de ese momento. Todos subidos al barco oficial, recibiendo maillots, txapelas y coronas. Aplausos y p\u00fablico reconocimiento a los esfuerzos. Deportistas que se vac\u00edan por amor al arte y que al final del ejercicio se repartir\u00e1n el importe de los premios conseguidos. Sumado todo es m\u00e1s que probable que no lleguen a la mensualidad de un jugador de los que ayer nos aterrorizaron en el estadio a la hora del \u00e1ngelus.<\/p>\n\n\n\n<p class=\" eplus-wrapper\">No esperaba ni el partido ofrecido ni el resultado final. Menos a\u00fan con aquel comienzo vertical, largo y con remate que traslad\u00f3 a la grada euforia y optimismo. Aquello no era presagio de lo que lleg\u00f3 despu\u00e9s. Un mazazo en toda regla, impropio de un equipo aspirante a cosas. Nos meten goles como churros. A pares. Aberdeen, Krasnodar, Real Madrid, Celta, Almer\u00eda y uno el Eibar que le sirvi\u00f3 para ganar. Los equipos se construyen desde atr\u00e1s y el nuestro chirr\u00eda, porque tanto gol en contra no es casualidad.<\/p>\n\n\n\n<p class=\" eplus-wrapper\">Se hab\u00edan decidido unas cosas y se hicieron otras. Me encantar\u00eda equivocarme, pero vamos a pagar una factura demasiado cara. Y por ahora no quiero ser m\u00e1s expl\u00edcito porque estamos en septiembre y queda mucho camino que recorrer, pero nunca ha sido bueno dudar de los porteros y del concepto defensivo de los equipos que sue\u00f1an con hacer algo grande. Matarile.<\/p>\n\n\n\n<p class=\" eplus-wrapper\">Luego, si quieres, hablaremos de la mala suerte, de los palos, de las ocasiones creadas y desaprovechadas. Cada cual lee los partidos como le apetece o interesa. Incluso Granero afirm\u00f3 al terminar que jugando quince encuentros contra el Almer\u00eda solo se perd\u00eda el de ayer, entendiendo que la superioridad entre ambos es indiscutible y que un c\u00famulo de adversidades decidi\u00f3 la contienda.<\/p>\n\n\n\n<p class=\" eplus-wrapper\">No habl\u00f3 de las jugadas a bal\u00f3n parado. Sacamos una docena de c\u00f3rners horrorosos, sin chispa, ni toque y mucho menos remate. Nos volvieron a meter otro a bal\u00f3n parado, porque se defiende zonal. La modernidad aliada con la ineficacia. Quienes sois asiduos a esta secci\u00f3n y pein\u00e1is canas recordar\u00e9is que in illo tempore un saque de esquina era una manada de guantadas de los defensas a los delanteros. Y si alguien remataba sal\u00eda herido. Ahora, no. Ahora, las defensas parecen poxpoli\u00f1as bailando aurreskus. Ni alma, ni coraje, ni tensi\u00f3n, ni nada. Caca, culo, pis.<\/p>\n\n\n\n<p class=\" eplus-wrapper\">Disfruto con los equipos y los deportistas pasionales, aquellos que se dejan el alma en cada intento. La actitud por encima de lo dem\u00e1s. La convicci\u00f3n, al servicio del objetivo. Ayer, el sufrido seguidor realista despidi\u00f3 al equipo con muchos aplausos en el descanso porque, aun perdiendo, lo hab\u00eda intentado de todos los modos y maneras. Todos cre\u00edmos que en la reanudaci\u00f3n se iban a comer al rival. \u00a1Qui\u00e1! Se abri\u00f3 el deambulatorio y nos perdimos dando vueltas entre el trascoro y las capillas radiales. Desaparecidos en combate. Sensaci\u00f3n de pobreza y obligada conexi\u00f3n con Houston porque tenemos un problema. \u00a1Y gordo!<\/p>\n\n\n\n<p class=\" eplus-wrapper\">Llegadas las siete de la tarde, harto de darle vueltas a la cabeza por lo acontecido y con ganas de nada, totalmente deprimido, me vest\u00ed de verde, sal\u00ed a la calle para recibir a los remeros de la Ama Guadalupekoa. Fuerte marejada en la adoquinada Kale Nagusia. Centenares de personas orgullosas de los deportistas que quieren y les representan. Aplaud\u00ed a su paso con la fuerza de quien agradece los esfuerzos y la entrega sin tapujos. Bien har\u00eda el consejo realista en homenajearles el pr\u00f3ximo domingo sobre el c\u00e9sped de Anoeta, aunque sea solo por intentar que sus jugadores se contagien por lo menos de la casta. Es que como te dec\u00eda al principio, la vida y el deporte ofrecen contrastes. Y no precisamente de pareceres.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Real Sociedad 1 &#8211; UD Almer\u00eda 2 (Jornada 4 &#8211; 21\/09\/2014) La vida est\u00e1 llena de contrastes. Existe muchas veces la posibilidad de elegir entre una cosa u otra. Trato de situarte en dos escenarios coincidentes ayer al mediod\u00eda. En el estudio de directo disponemos de dos grandes pantallas de televisi\u00f3n. Gracias a ellas tratamos [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":7848,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"editor_plus_copied_stylings":"{}","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[59],"tags":[],"class_list":["post-7982","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-beaterios-2014-2015"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/elbeaterio.es\/index.php\/wp-json\/wp\/v2\/posts\/7982","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elbeaterio.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elbeaterio.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elbeaterio.es\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/elbeaterio.es\/index.php\/wp-json\/wp\/v2\/comments?post=7982"}],"version-history":[{"count":1,"href":"https:\/\/elbeaterio.es\/index.php\/wp-json\/wp\/v2\/posts\/7982\/revisions"}],"predecessor-version":[{"id":8055,"href":"https:\/\/elbeaterio.es\/index.php\/wp-json\/wp\/v2\/posts\/7982\/revisions\/8055"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elbeaterio.es\/index.php\/wp-json\/wp\/v2\/media\/7848"}],"wp:attachment":[{"href":"https:\/\/elbeaterio.es\/index.php\/wp-json\/wp\/v2\/media?parent=7982"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elbeaterio.es\/index.php\/wp-json\/wp\/v2\/categories?post=7982"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elbeaterio.es\/index.php\/wp-json\/wp\/v2\/tags?post=7982"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}