{"id":7991,"date":"2014-11-29T00:00:00","date_gmt":"2014-11-28T22:00:00","guid":{"rendered":"https:\/\/elbeaterio.es\/index.php\/2014\/11\/29\/chespirito-y-carlos-vela\/"},"modified":"2025-05-27T19:27:09","modified_gmt":"2025-05-27T17:27:09","slug":"chespirito-y-carlos-vela","status":"publish","type":"post","link":"https:\/\/elbeaterio.es\/index.php\/2014\/11\/29\/chespirito-y-carlos-vela\/","title":{"rendered":"Chespirito y Carlos Vela"},"content":{"rendered":"\n<p class=\"has-gridlove-meta-color has-text-color has-link-color eplus-wrapper wp-elements-9d3c28efa0be846830bec6fda75fbc81\">Real Sociedad 3 &#8211; Elche CF 0 (Jornada 13 &#8211; 28\/11\/2014)<\/p>\n\n\n\n<p class=\" eplus-wrapper\">Un personaje mexicano, muy conocido en aquellos pagos, falleci\u00f3 mientras la Real ganaba al Elche. Roberto G\u00f3mez Bola\u00f1os hab\u00eda nacido en Ciudad de M\u00e9xico hace 85 a\u00f1os. Le dio tiempo a hacer muchas cosas y en su biograf\u00eda destacan facetas de actor, productor de televisi\u00f3n, dramaturgo, compositor, pero sobre todo int\u00e9rprete y creador de un personaje que todos conocen: El Chavo del Ocho. Algunas televisiones del sur de Am\u00e9rica siguen emitiendo cap\u00edtulos de la serie interpretada por este hombre al que todos conoc\u00edan como Chespirito.<\/p>\n\n\n\n<p class=\" eplus-wrapper\">Un periodista deportivo mexicano, Mart\u00edn del Palacio, al que sigo en las redes sociales, estaba viendo desde su pa\u00eds el partido de Anoeta y no dudaba en la dedicatoria de Vela al cielo si se enteraba de la muerte de este hombre porque la relaci\u00f3n de ambas familias es cercana y porque el propio actor, cuando el periodista apost\u00f3 por la vuelta del delantero realista a la selecci\u00f3n azteca, le envi\u00f3 un mensaje solidariz\u00e1ndose con la propuesta.<\/p>\n\n\n\n<p class=\" eplus-wrapper\">Chespirito era entra\u00f1able y muy futbolero. Ten\u00eda cara de buena persona y hoy ocupar\u00e1 las portadas de todos los medios de comunicaci\u00f3n en las que seguro dejan un hueco a la coincidencia con los tres goles del delantero realista. Abri\u00f3 pronto la lata con un tanto de cabeza, aprovechando el aclarado de Canales y el buen centro de Carlos Mart\u00ednez.<\/p>\n\n\n\n<p class=\" eplus-wrapper\">Dicen que a los gobiernos hay que darles cien d\u00edas para que sit\u00faen y se noten sus capacidades. El nuevo entrenador de la Real dispone de tiempo para reconducir la situaci\u00f3n y hacer del equipo lo que quiere, es decir, una Real entregada y que transmita emociones. Ese es su reto, adem\u00e1s de sumar los necesarios puntos, como anoche. El tiempo de calentamiento prepartido reflej\u00f3 la expectaci\u00f3n y el inter\u00e9s de los aficionados . Ambiente por todo lo alto antes de que rodara la pelota, sin que faltara en el tiempo la conversi\u00f3n de los m\u00f3viles en linternas a modo de cirios, como si quisieran aplaudir el acierto de su killer.<\/p>\n\n\n\n<p class=\" eplus-wrapper\">El calendario no le ayuda por la saturaci\u00f3n. Despu\u00e9s de Elche, la Copa en Oviedo. Luego, viaje a Villarreal, al que siguen un derbi, la vuelta de Copa y el partido de Valencia frente al Levante antes de los villancicos. Seis partidos en 20 d\u00edas. Y con la tradici\u00f3n que tenemos en semanas de tres, conf\u00edo en que le avisen para que no se lleve sobresaltos. El primero lo encontr\u00f3 en Riazor, porque despu\u00e9s de un digno primer tiempo, lleg\u00f3 un segundo casi calamitoso.<\/p>\n\n\n\n<p class=\" eplus-wrapper\">Supongo que con la incertidumbre de aquella respuesta, prepar\u00f3 el partido ante los ilicitanos. Confi\u00f3 en los mismos jugadores de Riazor con el \u00fanico cambio de Xabi Prieto en el once titular ocupando la plaza de Chory Castro. Esperaba una salida at\u00f3mica de las huestes giputxis. Tambi\u00e9n Escrib\u00e1. Atrincher\u00f3 a su gente por delante del meta Tyton y a ver venir. Y lo vio pronto. A los dos minutos, el partido en contra y la sensaci\u00f3n de que todo iba a ser imposible, porque los ilicitanos andan muy flojos de pegada y a estas horas lo que cuenta es ganar y sumar de tres en tres. Aplausos y a correr.<\/p>\n\n\n\n<p class=\" eplus-wrapper\">Y para terminar un apunte y que el cielo me perdone, pero como sigamos sumando personal al campo de ayudantes de Moyes, nos vamos a gastar el traspaso de Griezmann. Esta semana dos m\u00e1s se han unido a los que estaban. La n\u00f3mina actual cuenta con un titular (David), un ayudante (McKinlay), otro ayudante (Santana), un traductor con oficio futbol\u00edstico (Bretos), un preparador f\u00edsico (Larburu), un entrenador de porteros (Navajas), m\u00e1s la llegada de \u00faltima hora de un analista (Ruiz de Ocenda) y supongo que un \u201cesp\u00eda\u201d de rivales (Iturralde) y un readaptador (Samaniego). Tal vez me dejo alguno en el tintero. No cuento en este plantel ni a los m\u00e9dicos, ni a los auxiliares, ni al gabinete de comunicaci\u00f3n.<\/p>\n\n\n\n<p class=\" eplus-wrapper\">Sumados todos los que atienden al primer equipo del club, nos encontramos con m\u00e1s personal que todos los consejeros de los que dispone el lehendakari Urkullu para gestionar un territorio como este. Y tampoco voy a comparar los emolumentos de unos y otros, ni por supuesto la responsabilidad y la trascendencia social. Queda dicho que el f\u00fatbol va por su parte, a su bola, respecto del resto de mortales. Como me ha llamado la atenci\u00f3n y me parece un poco exagerado todo, lo comento.Por supuesto, esto no se relaciona con la capacidad y la idoneidad de quienes a esta hora ocupan la bancada txuri-urdin. \u00a1Faltar\u00eda m\u00e1s!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Real Sociedad 3 &#8211; Elche CF 0 (Jornada 13 &#8211; 28\/11\/2014) Un personaje mexicano, muy conocido en aquellos pagos, falleci\u00f3 mientras la Real ganaba al Elche. Roberto G\u00f3mez Bola\u00f1os hab\u00eda nacido en Ciudad de M\u00e9xico hace 85 a\u00f1os. Le dio tiempo a hacer muchas cosas y en su biograf\u00eda destacan facetas de actor, productor de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":7857,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"editor_plus_copied_stylings":"{}","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[59],"tags":[],"class_list":["post-7991","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-beaterios-2014-2015"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/elbeaterio.es\/index.php\/wp-json\/wp\/v2\/posts\/7991","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elbeaterio.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elbeaterio.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elbeaterio.es\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/elbeaterio.es\/index.php\/wp-json\/wp\/v2\/comments?post=7991"}],"version-history":[{"count":1,"href":"https:\/\/elbeaterio.es\/index.php\/wp-json\/wp\/v2\/posts\/7991\/revisions"}],"predecessor-version":[{"id":8051,"href":"https:\/\/elbeaterio.es\/index.php\/wp-json\/wp\/v2\/posts\/7991\/revisions\/8051"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elbeaterio.es\/index.php\/wp-json\/wp\/v2\/media\/7857"}],"wp:attachment":[{"href":"https:\/\/elbeaterio.es\/index.php\/wp-json\/wp\/v2\/media?parent=7991"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elbeaterio.es\/index.php\/wp-json\/wp\/v2\/categories?post=7991"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elbeaterio.es\/index.php\/wp-json\/wp\/v2\/tags?post=7991"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}