{"id":7999,"date":"2015-01-12T00:00:00","date_gmt":"2015-01-11T22:00:00","guid":{"rendered":"https:\/\/elbeaterio.es\/index.php\/2015\/01\/12\/un-dos-tres-al-escondite-ingles\/"},"modified":"2025-05-27T19:27:09","modified_gmt":"2025-05-27T17:27:09","slug":"un-dos-tres-al-escondite-ingles","status":"publish","type":"post","link":"https:\/\/elbeaterio.es\/index.php\/2015\/01\/12\/un-dos-tres-al-escondite-ingles\/","title":{"rendered":"\u00a1Un dos tres, al escondite ingl\u00e9s!"},"content":{"rendered":"\n<p class=\"has-gridlove-meta-color has-text-color has-link-color eplus-wrapper wp-elements-35fef8c191c7ef69c28f7714ff716db9\">Granada CF 1 &#8211; Real Sociedad 1 (Jornada 18 &#8211; 11\/01\/2015)<\/p>\n\n\n\n<p class=\" eplus-wrapper\">La cuesta de enero no oculta sus rampas y pone de manifiesto carencias y tendencias. Hasta tal punto que aparecen las verg\u00fcenzas en grado sumo y ayuda a desmontar viejos ardides que, por usados y manidos, se instalan como ciertos y no lo son de ning\u00fan modo. Me explico.<\/p>\n\n\n\n<p class=\" eplus-wrapper\">Uno. Como a alguien se le ocurra decir que la liga es la mejor del mundo, le remito un surtidito de partidos grabados para que los visione y compruebe. Hay una cantidad de tru\u00f1os y petardos de dif\u00edcil digesti\u00f3n. Los encuentros de los viernes y aquellos que se juegan los lunes son normalmente infumables. Cada vez se juega menos y peor.<\/p>\n\n\n\n<p class=\" eplus-wrapper\">Dos. Como alguien se adorne defendiendo la calidad del arbitraje espa\u00f1ol, le adjunto con cari\u00f1o el listado que circula en los \u00faltimos d\u00edas en el que aparecen los mejores colegiados internacionales del mundo. Entre los diez primeros hay uno que, adem\u00e1s, no me gusta nada.<\/p>\n\n\n\n<p class=\" eplus-wrapper\">Tres. Como alguien tenga a bien contarme loas y alabanzas del juego de la Real, le regalo en el mismo lote un escapulario de San Onofre y una estampa de la Virgen de Coromoto. Si es capaz de descubrir maravillas en el actual comportamiento del equipo, es obvio que se encuentra en plena catarsis tocando el cielo e imbuido de misticismo.<\/p>\n\n\n\n<p class=\" eplus-wrapper\">El escondite ingl\u00e9s. Nuestro t\u00e9cnico se empe\u00f1a en cabezonadas. Despu\u00e9s de explicar el viernes, con bastantes pelos y algunas se\u00f1ales, el estado f\u00edsico de la plantilla y los posibles s\u00edes y noes, se descolg\u00f3 el s\u00e1bado ocultando de nuevo la lista de convocados y mandando a la pu\u00f1eta a los fot\u00f3grafos que acudieron a despedir al equipo en el aeropuerto: \u201cThe photographs are prohibited\u201d (o como se diga).<\/p>\n\n\n\n<p class=\" eplus-wrapper\">La nueva filosof\u00eda (es co\u00f1a) que se implanta en los comportamientos grupales o corales. Si al anterior entrenador que se sentaba en nuestro banquillo se le ocurre una sola vez ocultar la convocatoria, le caen adoquines a mansalva. Y no me refiero a los caramelos t\u00edpicos zaragozanos.<\/p>\n\n\n\n<p class=\" eplus-wrapper\">Todas estas cosas estar\u00edan muy bien y podr\u00edan entenderse si vinieran acompa\u00f1adas de un cambio estupendo en la forma de desplegar el juego, en el modo de atacar y defender, en los resultados, y sobre todo en la empat\u00eda del equipo con sus aficionados. Cautivar que dir\u00edan los analistas. Por ahora, de todo esto tenemos poco por no decir que hemos perdido parte de las antiguas esencias.<\/p>\n\n\n\n<p class=\" eplus-wrapper\">A eso de las seis de la tarde conocimos la alineaci\u00f3n, con Elustondo y Pardo en la medular y con Vela en punta que es donde luce poco y es menos efectivo. Lo dem\u00e1s, lo esperado. Luego, llega el partido y el desarrollo del mismo. Es obvio que el equipo se atrinchera y defiende con m\u00e1s contundencia. No es f\u00e1cil hacerle ocasiones, aunque sea a costa de desaparecer m\u00e1s all\u00e1 de la divisoria. Un pase formidable encontr\u00f3 a Canales y el penalti no lo desaprovech\u00f3 Vela, que cada vez que juega de 9 sufre, no disfruta y se enfurru\u00f1a. Ya estaba el partido con la cuesti\u00f3n m\u00e1s complicada resuelta: hacer gol. Ventaja al descanso y la esperanza de que en el segundo tiempo, el equipo luzca galones, coja el bal\u00f3n y trate de meterlo para sentenciar en la porter\u00eda de Oier, que hizo un par de paradas de m\u00e9rito.<\/p>\n\n\n\n<p class=\" eplus-wrapper\">Sin embargo, nada de eso pas\u00f3. Tampoco el Granada est\u00e1 para cohetes. El p\u00fablico pitaba de lo lindo a su delantero, El Arabi, el fichaje m\u00e1s caro de la historia del club que no ejerce como definidor. Le cambiaron. Salieron Isaac, Riki, Piti, sin perder el norte de la banda derecha por donde se hinchaban de atacar y atacar, sobre todo desde que Chory dej\u00f3 el terreno.<\/p>\n\n\n\n<p class=\" eplus-wrapper\">Como las canas no son de te\u00f1irme y cuando el rival merodea en nuestra \u00e1rea suelen pasar cosas desagradables, surgi\u00f3 el penalti pardillo de turno. Como en la cancha del Levante y en tantas otras en las que nos falta tensi\u00f3n y ambici\u00f3n para asegurar los puntos y las victorias. Se nos han ido cuatro por una falta de tensi\u00f3n que castiga lo raqu\u00edtico del juego. Podemos esconder la lista de convocados, la alineaci\u00f3n, pero la prueba del algod\u00f3n es irrefutable. Los azulejos no brillan ni de lejos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Granada CF 1 &#8211; Real Sociedad 1 (Jornada 18 &#8211; 11\/01\/2015) La cuesta de enero no oculta sus rampas y pone de manifiesto carencias y tendencias. Hasta tal punto que aparecen las verg\u00fcenzas en grado sumo y ayuda a desmontar viejos ardides que, por usados y manidos, se instalan como ciertos y no lo son [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":7865,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"editor_plus_copied_stylings":"{}","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[59],"tags":[],"class_list":["post-7999","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-beaterios-2014-2015"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/elbeaterio.es\/index.php\/wp-json\/wp\/v2\/posts\/7999","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elbeaterio.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elbeaterio.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elbeaterio.es\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/elbeaterio.es\/index.php\/wp-json\/wp\/v2\/comments?post=7999"}],"version-history":[{"count":1,"href":"https:\/\/elbeaterio.es\/index.php\/wp-json\/wp\/v2\/posts\/7999\/revisions"}],"predecessor-version":[{"id":8047,"href":"https:\/\/elbeaterio.es\/index.php\/wp-json\/wp\/v2\/posts\/7999\/revisions\/8047"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elbeaterio.es\/index.php\/wp-json\/wp\/v2\/media\/7865"}],"wp:attachment":[{"href":"https:\/\/elbeaterio.es\/index.php\/wp-json\/wp\/v2\/media?parent=7999"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elbeaterio.es\/index.php\/wp-json\/wp\/v2\/categories?post=7999"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elbeaterio.es\/index.php\/wp-json\/wp\/v2\/tags?post=7999"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}