{"id":8003,"date":"2015-02-01T00:00:00","date_gmt":"2015-01-31T22:00:00","guid":{"rendered":"https:\/\/elbeaterio.es\/index.php\/2015\/02\/01\/la-vida-sigue-igual-y-mas-triste\/"},"modified":"2025-05-27T19:27:09","modified_gmt":"2025-05-27T17:27:09","slug":"la-vida-sigue-igual-y-mas-triste","status":"publish","type":"post","link":"https:\/\/elbeaterio.es\/index.php\/2015\/02\/01\/la-vida-sigue-igual-y-mas-triste\/","title":{"rendered":"La vida sigue igual y m\u00e1s triste"},"content":{"rendered":"\n<p class=\"has-gridlove-meta-color has-text-color has-link-color eplus-wrapper wp-elements-6b6fe6943f2440c5a3c1456b4d66f8e1\">Real Madrid 4 &#8211; Real Sociedad 1 (Jornada 21 &#8211; 31\/01\/2015)<\/p>\n\n\n\n<p class=\" eplus-wrapper\">Termin\u00e9 de ver el partido que disputaban Artola y Albisu en el front\u00f3n de Bergara cuando las manecillas del reloj se\u00f1alaban la media noche. Mir\u00e9 por \u00faltima vez el ordenador. Ning\u00fan correo interesante en mi cuenta de email y ninguna noticia oficial en la web txuri-urdin. As\u00ed que, sin sobresaltos, fui bajando persianas, apagando radiadores y luces antes de meterme en la cama. Limpieza de pi\u00f1os y al edred\u00f3n.<\/p>\n\n\n\n<p class=\" eplus-wrapper\">Es imposible que duerma sin encender la radio y escuchar de fondo el programa que sea, con el volumen en su justo t\u00e9rmino, sin molestar y ayudando a que los p\u00e1rpados se cierren y la cabeza deje de dar vueltas. En esas estaba cuando el locutor de turno anuncia que a ultim\u00edsima hora la Real, seg\u00fan la LFP, incorporaba a un chico sueco del AIK Solna que atiende por Bahoui. Pens\u00e9 en los compa\u00f1eros de prensa escrita porque a esas horas de la noche hay un verbo que define la situaci\u00f3n perfectamente, o un sustantivo que acaba en onada, que es lo mismo.<\/p>\n\n\n\n<p class=\" eplus-wrapper\">Pocos minutos despu\u00e9s el mismo locutor anuncia que el fichaje no se lleva a cabo porque los suecos se han hecho los idem y renuncian a cerrar la operaci\u00f3n. Vuelvo otra vez a acordarme mucho m\u00e1s de quienes tratan de cerrar la edici\u00f3n de este medio, pero ahora obligados a levantar una p\u00e1gina y completarla con otra informaci\u00f3n mientras la rotativa espera y las prisas no exentas de tensi\u00f3n se convierten en una presi\u00f3n a\u00f1adida.<\/p>\n\n\n\n<p class=\" eplus-wrapper\">A la espera de que alguien de la santa casa aparezca en una mesa y cuente la historia ante el respetable, caben de entrada dos conclusiones r\u00e1pidas. La LFP se precipita y hace el rid\u00edculo (uno m\u00e1s) anunciando lo que, a lo visto, no se ha producido. Mucho m\u00e1s grave a\u00fan es el hecho de que la filtraci\u00f3n producida levanta la liebre de un futbolista al resto de entidades. Esa gravedad depender\u00e1 del comportamiento en las pr\u00f3ximas horas del club sueco en relaci\u00f3n con el jugador. Si lo traspasa a otra entidad continental, les clasificaremos donde corresponde, pero si sigue en sus filas? date por jodido. Da\u00f1os y perjuicios.<\/p>\n\n\n\n<p class=\" eplus-wrapper\">La otra parte se relaciona con la Real. Ser\u00eda bueno, por salud e higiene, que alguien apareciera ante los micr\u00f3fonos y contara qui\u00e9n negocia, qui\u00e9n decide los fichajes, qui\u00e9n determina las inversiones y a qui\u00e9n corresponde la responsabilidad en cada situaci\u00f3n, aunque solo sea por aclarar el paisaje y el paisanaje. Cansa bastante, por aburrido, que siempre el culpable sea el mismo y a lo mejor tenga poco que ver, o nada, en el asunto. Si en este club que nos ocupa no existieran Loren y Elustondo, el mayor, necesitar\u00edamos un Taigeto como el de los espartanos.<\/p>\n\n\n\n<p class=\" eplus-wrapper\">As\u00ed que mala y decepcionante gesti\u00f3n si pretend\u00edan lograr adquisiciones. Ni refuerzos, ni fichajes. Lo \u00fanico concreto, que no es poco, deja una plantilla con lesionados, dos m\u00e1s en Chamart\u00edn, que deben recuperarse para sumar y con futbolistas que deben dar un paso al frente y competir m\u00e1s y mejor. Y si adem\u00e1s el entrenador consigue de ellos que el rendimiento y el n\u00famero de puntos y victorias sean mayores, estaremos en una situaci\u00f3n necesaria de agradable confort y no la actual que deprime.<\/p>\n\n\n\n<p class=\" eplus-wrapper\">En esa direcci\u00f3n el partido del Bernab\u00e9u no llamaba al optimismo por mucho que faltara Ronaldo. Lejos de Anoeta la Real ha dado pena todo el a\u00f1o y, aunque se adelantara con un golazo de Aritz Elustondo, el resto sigui\u00f3 un guion triste que empez\u00f3 a escribirse cuando se conoci\u00f3 el accidente en el que fallec\u00eda un chaval que viajaba con sus amigos a Madrid para animar al equipo que llevaba en su coraz\u00f3n.<\/p>\n\n\n\n<p class=\" eplus-wrapper\">Despu\u00e9s sigui\u00f3 con las lesiones de Vela y Canales, con errores impropios de un equipo profesional y con una falta de tensi\u00f3n y competitividad que dan que pensar y preocupan a quienes asistimos a este desprop\u00f3sito en el que est\u00e1 sumido el equipo y no s\u00e9 si la entidad. S\u00e9 que estos partidos son poco accesibles y en ellos abr\u00eda y cerraba par\u00e9ntesis, pero las sensaciones que el equipo ofrece no llaman ni al optimismo, ni a la esperanza. La vida sigue igual, pero m\u00e1s triste por la muerte de un joven. Brazaletes negros, minuto de silencio y partido decepcionante. Solo Rulli cumpli\u00f3 como se exig\u00eda.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Real Madrid 4 &#8211; Real Sociedad 1 (Jornada 21 &#8211; 31\/01\/2015) Termin\u00e9 de ver el partido que disputaban Artola y Albisu en el front\u00f3n de Bergara cuando las manecillas del reloj se\u00f1alaban la media noche. Mir\u00e9 por \u00faltima vez el ordenador. Ning\u00fan correo interesante en mi cuenta de email y ninguna noticia oficial en la [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":7869,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"editor_plus_copied_stylings":"{}","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[59],"tags":[],"class_list":["post-8003","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-beaterios-2014-2015"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/elbeaterio.es\/index.php\/wp-json\/wp\/v2\/posts\/8003","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elbeaterio.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elbeaterio.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elbeaterio.es\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/elbeaterio.es\/index.php\/wp-json\/wp\/v2\/comments?post=8003"}],"version-history":[{"count":1,"href":"https:\/\/elbeaterio.es\/index.php\/wp-json\/wp\/v2\/posts\/8003\/revisions"}],"predecessor-version":[{"id":8062,"href":"https:\/\/elbeaterio.es\/index.php\/wp-json\/wp\/v2\/posts\/8003\/revisions\/8062"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elbeaterio.es\/index.php\/wp-json\/wp\/v2\/media\/7869"}],"wp:attachment":[{"href":"https:\/\/elbeaterio.es\/index.php\/wp-json\/wp\/v2\/media?parent=8003"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elbeaterio.es\/index.php\/wp-json\/wp\/v2\/categories?post=8003"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elbeaterio.es\/index.php\/wp-json\/wp\/v2\/tags?post=8003"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}