{"id":8796,"date":"2020-07-14T15:37:00","date_gmt":"2020-07-14T13:37:00","guid":{"rendered":"https:\/\/elbeaterio.es\/?p=8796"},"modified":"2025-05-30T15:45:20","modified_gmt":"2025-05-30T13:45:20","slug":"actitud-amenazante","status":"publish","type":"post","link":"https:\/\/elbeaterio.es\/index.php\/2020\/07\/14\/actitud-amenazante\/","title":{"rendered":"Actitud Amenazante"},"content":{"rendered":"\n<p class=\" eplus-wrapper\"><\/p>\n\n\n\n<figure class=\" wp-block-table eplus-wrapper\"><table><thead><tr><th class=\"has-text-align-center\" data-align=\"center\">Villarreal CF 1-2 Real Sociedad<\/th><\/tr><\/thead><tbody><tr><td class=\"has-text-align-center\" data-align=\"center\">Jornada 36 Liga &#8211; 13\/07\/2020<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p class=\" eplus-wrapper\">El equipo volvi\u00f3 ayer a dar una lecci\u00f3n de compromiso. En un partido en el que no iba a encontrar una sola facilidad, logra tres puntos que le mantienen vivo a la espera de dos finales en tres d\u00edas. Es lo que hay. Toca esperar hasta el final y seguir confiando en la actitud generosa de un grupo comprometido y solidario, al que le han faltado al respeto de modo tremendo desde que la competici\u00f3n se reanud\u00f3 de esta manera.<\/p>\n\n\n\n<p class=\" eplus-wrapper\">Al presidente de la Real Sociedad le han recetado tres partidos de suspensi\u00f3n, porque el \u00e1rbitro del encuentro ante el Granada tir\u00f3 de teclado para contar el momento en que Aperribay baj\u00f3 al t\u00fanel de vestuarios para decirle, de buenas maneras y sin insultos, lo que llevamos pensando muchos desde hace varias semanas. He le\u00eddo el acta y en ella, adem\u00e1s de relatar lo que escucharon, adorna el escenario con las dos palabras que titulan este comentario. \u00a1Actitud amenazante!<\/p>\n\n\n\n<p class=\" eplus-wrapper\">\u00bfQu\u00e9 pretend\u00eda el trencilla al escribirlo? \u00bfEn qu\u00e9 consiste esa actitud y c\u00f3mo se cataloga? Da pie a todo tipo de interpretaciones. Puestos a cachondearnos del momento y dejando volar la imaginaci\u00f3n, entra dentro de lo posible que Jokin se quitara un mocas\u00edn, lo agarrara con la mano derecha e hiciera un gesto como de darle tast\u00e1s en el culo o tir\u00e1rselo a la cabeza. Cabe que se quitara el cintur\u00f3n, se bajara los pantalones y le hiciera un calvo. A lo mejor no estaba solo, sino acompa\u00f1ado de algunos consejeros, con trajes de alabardero, lanza en ristre, como si le fueran a pinchar estilo merienda de tribu india. Tal vez, cerr\u00f3 los pu\u00f1os y, en plan Mike Tyson, simulara que le iba a lanzar un uppercut al ment\u00f3n. \u00bfSe encontr\u00f3 en el pasillo con un balde de agua, y agarr\u00f3 la fregona en plan akuilu? Todas estas posibilidades pueden catalogarse como amenazantes. Ser\u00eda bueno por la salud de todos y la credibilidad de quien escribe que relatara en qu\u00e9 consisti\u00f3 dicha actitud.<\/p>\n\n\n\n<p class=\" eplus-wrapper\">Y lo escribe un \u00e1rbitro que forma parte de un colectivo que est\u00e1 dando pena y ense\u00f1ando sus verg\u00fcenzas desde que se reanud\u00f3 el campeonato. No hay por d\u00f3nde agarrarlo. Se contradicen ellos mismos decidiendo diferente seg\u00fan los casos. Y lo triste es que muchos de los que se equivocan, tanto en el c\u00e9sped como en la sala de m\u00e1quinas, llevan la escarapela internacional. Da la sensaci\u00f3n muchas veces que desconocen el reglamento o lo interpretan mal, o les confunden. Cada vez m\u00e1s inseguros, tiemblan en las jugadas de conflicto. Temen cuando se les descubren los errores, porque pierden credibilidad por arrobas. No aguantan la presi\u00f3n y se ponen rojos, una mezcla de sofoco y rid\u00edculo. No hay peor momento del arbitraje espa\u00f1ol que el actual. Cuantos m\u00e1s recursos ponen a su disposici\u00f3n, peor. Rompo aqu\u00ed una lanza en favor de unos cuantos \u00e1rbitros de la categor\u00eda de plata a los que veo un mont\u00f3n de veces. Sin \u00e1nimo de ser chauvinistas, los dos colegiados guipuzcoanos Gorka Sagu\u00e9s y Aitor Gorostegi ofrecen bastante mejor nivel que el de muchos de los que nos caen en suerte y militan en Primera. Con el dineral que les cuesta el arbitraje, los clubes (todos se quejan de lo mismo) deber\u00edan ponerse las pilas e intervenir por el bien de la comunidad. Por cierto, no me cabe la menor duda de que si los aficionados acudieran a los estadios, no estaban pasando ni la mitad de las cosas que suceden y que desquician a los jugadores y todos sus entornos. Ayer una tarjeta roja a un miembro del banquillo txuri-urdin.<\/p>\n\n\n\n<p class=\" eplus-wrapper\">Como esto no se sostiene de ning\u00fan modo, a los equipos les han obligado a jugar tres veces por semana, a competir muchas veces con gente que no est\u00e1 en sus mejores condiciones, sin las horas necesarias de descanso y recuperaci\u00f3n, someti\u00e9ndoles a una tortura f\u00edsica y psicol\u00f3gica. No hay futbolista que soporte este traj\u00edn. La lista de lesiones es interminable y en esas condiciones poco se puede exigir. En medio de esa realidad, Imanol y lo que queda de los suyos viajaron a Vila-real. El t\u00e9cnico eligi\u00f3 lo que pudo y a medida que las cosas sucedieron debi\u00f3 modificar el plan inicial. Isak, a quien Asenjo le hizo un parad\u00f3n, se qued\u00f3 en la caseta durante el descanso. Poco despu\u00e9s del primer cambio, sent\u00f3 a Barrenetxea porque debe cuidarle. Lo mismo que a sus compa\u00f1eros m\u00e1s exigidos. \u00a1Se nos agota el hielo! Como es necesario llegar al final sin que se rompa ninguno m\u00e1s, aguantas como puedes y metes en la lista de convocados a medio Sanse, jugadores que est\u00e1n a punto de cumplir un a\u00f1o al pie del ca\u00f1\u00f3n sin vacaciones ni respiros. Bravo, tambi\u00e9n, por ellos.<\/p>\n\n\n\n<p class=\" eplus-wrapper\">La condici\u00f3n f\u00edsica no es la recomendable y la an\u00edmica, probablemente, tampoco. Pese a ello, el equipo sigue dando la cara desde el pitido inicial de la reanudaci\u00f3n del campeonato. Y yo, al menos, no tengo nada que recriminarle. Todo lo contrario. Con poca fortuna y demasiados atropellos sigue haciendo camino sin perder la compostura. Su actitud es cualquier cosa menos amenazante. Cuando consigue victorias como la de ayer en Vila-real recibe el premio que merece y reconforta a toda la feligres\u00eda que asiste at\u00f3nita al sainete que nos han montado. Dos goles que valen su peso en oro. Dos remates de cabeza en acciones a bal\u00f3n parado, en sendos centros de calidad. Para eso est\u00e1n, entre otras cosas, Martintxo y Mikel. Todos los goles valen lo mismo, pero que Willian Jos\u00e9 y Diego Llorente sean los protagonistas se celebra de modo especial despu\u00e9s de los latigazos que les han ca\u00eddo en jornadas precedentes, sobre todo al central. Entiendo c\u00f3mo se manifest\u00f3 en la celebraci\u00f3n.<\/p>\n\n\n\n<p class=\" eplus-wrapper\">Me da verg\u00fcenza hablar de finales, porque s\u00e9 que al entrenador no le gusta, pero el partido de este jueves en Anoeta parece decisivo para la suerte \u00faltima de la clasificaci\u00f3n. Llega el Sevilla que, gracias a la Real, certific\u00f3 de modo matem\u00e1tico su presencia en la pr\u00f3xima Champions, porque el Villarreal ya no le alcanza. Por los puestos europeos, pelean unos cuantos que van por delante y por detr\u00e1s de los realistas. Bueno ser\u00eda tratar de superar a los andaluces, certificar la posici\u00f3n con premio y disfrutar de unas vacaciones prolongadas. \u00bfD\u00f3nde hay que firmar?<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Villarreal CF 1-2 Real Sociedad Jornada 36 Liga &#8211; 13\/07\/2020 El equipo volvi\u00f3 ayer a dar una lecci\u00f3n de compromiso. En un partido en el que no iba a encontrar una sola facilidad, logra tres puntos que le mantienen vivo a la espera de dos finales en tres d\u00edas. Es lo que hay. Toca esperar [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":8797,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"editor_plus_copied_stylings":"{}","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[54],"tags":[],"class_list":["post-8796","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-beaterios-2019-2020"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/elbeaterio.es\/index.php\/wp-json\/wp\/v2\/posts\/8796","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elbeaterio.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elbeaterio.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elbeaterio.es\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/elbeaterio.es\/index.php\/wp-json\/wp\/v2\/comments?post=8796"}],"version-history":[{"count":2,"href":"https:\/\/elbeaterio.es\/index.php\/wp-json\/wp\/v2\/posts\/8796\/revisions"}],"predecessor-version":[{"id":8805,"href":"https:\/\/elbeaterio.es\/index.php\/wp-json\/wp\/v2\/posts\/8796\/revisions\/8805"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elbeaterio.es\/index.php\/wp-json\/wp\/v2\/media\/8797"}],"wp:attachment":[{"href":"https:\/\/elbeaterio.es\/index.php\/wp-json\/wp\/v2\/media?parent=8796"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elbeaterio.es\/index.php\/wp-json\/wp\/v2\/categories?post=8796"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elbeaterio.es\/index.php\/wp-json\/wp\/v2\/tags?post=8796"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}