{"id":978,"date":"2013-04-07T06:02:16","date_gmt":"2013-04-07T06:02:16","guid":{"rendered":"http:\/\/localhost\/joomla\/2013\/04\/07\/el-chico-que-anunciaba-calzoncillos\/"},"modified":"2025-05-28T15:49:41","modified_gmt":"2025-05-28T13:49:41","slug":"el-chico-que-anunciaba-calzoncillos","status":"publish","type":"post","link":"https:\/\/elbeaterio.es\/index.php\/2013\/04\/07\/el-chico-que-anunciaba-calzoncillos\/","title":{"rendered":"El chico que anunciaba calzoncillos"},"content":{"rendered":"\n<p class=\" eplus-wrapper\"><\/p>\n\n\n\n<figure class=\" wp-block-table eplus-wrapper\"><table><thead><tr><th class=\"has-text-align-center\" data-align=\"center\">Real Sociedad 4 &#8211; M\u00e1laga CF 2<\/th><\/tr><\/thead><tbody><tr><td class=\"has-text-align-center\" data-align=\"center\">Jornada 30 Liga &#8211; 06\/04\/2013<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p class=\" eplus-wrapper\"><\/p>\n\n\n<p>Alberto de la Bella es uno de esos futbolistas que lleg\u00f3 al escaparate principal de la competici\u00f3n por los caminos m\u00e1s inveros\u00edmiles y, por supuesto, impensables. Un d\u00eda le rescataron del filial sevillista. Contaba en una entrevista aqu\u00ed publicada, y que nunca niega, que aquel verano estando de vacaciones vio en su m\u00f3vil una llamada perdida que comenzaba por \u201c943\u201d. Crey\u00f3 que le llamaban de Ir\u00fan, porque el Real Uni\u00f3n hab\u00eda ascendido de categor\u00eda y a lo mejor se interesaban.<\/p>\n<p><!--more--><\/p>\n<p>Nunca pens\u00f3 que fuera la Real, en Segunda, quien realmente hubiera apretado las teclas de aquel n\u00famero que a\u00fan conserva en su celular. Luego, las cosas siguieron su cauce y concret\u00f3 el acuerdo con el club cuya camiseta defiende con absoluta honradez. Aquella decisi\u00f3n conllevaba riesgo para las dos partes, porque pudiera pensarse que la adaptaci\u00f3n al entorno no iba a ser f\u00e1cil y porque su rendimiento era una inc\u00f3gnita.<\/p>\n<\/p>\n<p>Han pasado unas cuantas temporadas y se ha hecho con el puesto en propiedad y se atreve a chutar a puerta y meter goles y ser feliz. Ayer firm\u00f3 el 3.001 que vale lo mismo que el anterior y el posterior. Lo celebra con m\u00e1s pasi\u00f3n que los habituales, precisamente por eso. El remate ante el M\u00e1laga fue espl\u00e9ndido, como el partido que se peg\u00f3 y la temporada que est\u00e1 ofreciendo. Eso es lo que ve el espectador, pero quienes le conocen y comparten con \u00e9l vestuario, objetivos y experiencias saben que es un t\u00edo humilde, perfectamente adaptado y que cumple intachable el rol que le corresponde en ese colectivo.<\/p>\n<p>Cuando lleg\u00f3 aqu\u00ed era un desconocido que no sal\u00eda en los cromos. No sonaba. Tiramos todos de manual y de p\u00e1ginas web. De repente le encontramos desfilando por las pasarelas y ense\u00f1ando calzoncillos de una marca que acababa en \u201cbergs\u201d. \u00a1Ay, madre!. Pronto aprendi\u00f3 lo que val\u00eda un peine y entendi\u00f3 que lo prioritario es creer en uno mismo y dejarse de flores y p\u00e1jaros. Hacer grupo y plantearse objetivos, colectivos y personales. Ahora que est\u00e1 en un momento espl\u00e9ndido le servir\u00e1 de referencia aquel tiempo en que lo pas\u00f3 mal, cuando el entrenador de turno decidi\u00f3 sentarle para darle su puesto a Mikel Gonz\u00e1lez. Dura situaci\u00f3n de la que supo sacar conclusiones y ofrecer respuestas.<\/p>\n<p>Ayer es muy probable que cuando le dijeron que no jugaba Joaqu\u00edn, respirara profundamente, se liberara de la autopresi\u00f3n impuesta y decidiera echar el resto para completar un partido del que poder presumir. Lo mismo que los seguidores del equipo, inmensamente felices por verles ganar y ocupar un puesto clasificatorio que da v\u00e9rtigo y orgullo al mismo tiempo.<\/p>\n<p>Te preguntar\u00e1s, a lo mejor, por qu\u00e9 se me ocurre hablar de este chico catal\u00e1n de Santa Coloma de Gramanet. Precisamente, por eso, porque pertenece a la plantilla y es uno m\u00e1s de sus componentes. Ayer Vela marc\u00f3 el 3.000, Alberto el 3001, Griezmann firm\u00f3 el 3002 e I\u00f1igo Mart\u00ednez, el 3003. \u00bfCabe m\u00e1s pluralidad?. Esa es la Real de hoy, la que dispone de un equipo formidable, que se lleva magn\u00edficamente y que, fuera de las instalaciones que comparte, prolonga la relaci\u00f3n y los proyectos. Ese es un valor a\u00f1adido, una riqueza, que apetece destacar. El grupo, por encima de las individualidades.<\/p>\n<p>Estas cosas le han hecho fuerte y cohesionado. Parece que d\u00e9 igual enfrentarse al M\u00e1laga o al Apurtuarte. Pasan los minutos y no sucede nada. Hasta que, de repente, como si alguien tocara trompeta a rebato, zafarrancho colectivo y gol en la primera llegada. Segundo toque de clar\u00edn y nuevo tanto; tercer s\u00f3lo y otro al saco. Es decir que, en un santiam\u00e9n partido resuelto. Luego, adornos, otros goles, lesiones, taconazos gozosos y ambiente festivo en la grada.<\/p>\n<p>En medio de semejante algazara este chico del que hoy me ocupo peg\u00f3 un pepinazo que entr\u00f3 ajustadito al palo para que el pedazo de portero que hab\u00eda enfrente no llegara pese a estirarse. Lo celebr\u00f3, lo disfrut\u00f3 y lo a\u00f1adi\u00f3 al elenco de los tantos hermosos que el partido ofreci\u00f3. Siguen haciendo camino, aunque haya bajas, lesiones, ansiedad. Cada vez est\u00e1 m\u00e1s cerca el premio. Muchos saben que lo han pasado mal en distintos momentos del pasado reciente y aspiran a resarcirse. Se lo merecen.<\/p>\n<p>Entre ellos, Alberto de la Bella, ese futbolista que un d\u00eda se apunt\u00f3 como modelo de gallumbos belgas y hoy sigue siendo modelo, modelo de fidelidad y agradecimiento a unos colores, a una camiseta, a unos compa\u00f1eros, a un club. En eso, afortunadamente, no est\u00e1 solo.<\/p>\n<p>Del partido voy a decir poco. O nada. Me encantar\u00eda que los andaluces pasaran la eliminatoria, porque lo suyo es de m\u00e9rito. Viven en la inc\u00f3gnita permanente, bajo la sombra de un jeque virtual, con un entrenador formidable capaz de convencerles de que s\u00f3lo hab\u00eda un camino que beneficiaba a todos. Le creyeron y lo est\u00e1n siguiendo a pies juntillas con m\u00e9rito y acierto. Ayer las rotaciones y los sue\u00f1os futuros les condenaron. Al otro lado de la l\u00ednea divisoria hab\u00eda un equipo humilde y con hambre de victorias.<\/p>\n<\/p>","protected":false},"excerpt":{"rendered":"<p>Real Sociedad 4 &#8211; M\u00e1laga CF 2 Jornada 30 Liga &#8211; 06\/04\/2013 Alberto de la Bella es uno de esos futbolistas que lleg\u00f3 al escaparate principal de la competici\u00f3n por los caminos m\u00e1s inveros\u00edmiles y, por supuesto, impensables. Un d\u00eda le rescataron del filial sevillista. Contaba en una entrevista aqu\u00ed publicada, y que nunca niega, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":8412,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"editor_plus_copied_stylings":"{}","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[38],"tags":[],"class_list":["post-978","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-beaterios-2012-2013"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/elbeaterio.es\/index.php\/wp-json\/wp\/v2\/posts\/978","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elbeaterio.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elbeaterio.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elbeaterio.es\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/elbeaterio.es\/index.php\/wp-json\/wp\/v2\/comments?post=978"}],"version-history":[{"count":3,"href":"https:\/\/elbeaterio.es\/index.php\/wp-json\/wp\/v2\/posts\/978\/revisions"}],"predecessor-version":[{"id":8419,"href":"https:\/\/elbeaterio.es\/index.php\/wp-json\/wp\/v2\/posts\/978\/revisions\/8419"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elbeaterio.es\/index.php\/wp-json\/wp\/v2\/media\/8412"}],"wp:attachment":[{"href":"https:\/\/elbeaterio.es\/index.php\/wp-json\/wp\/v2\/media?parent=978"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elbeaterio.es\/index.php\/wp-json\/wp\/v2\/categories?post=978"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elbeaterio.es\/index.php\/wp-json\/wp\/v2\/tags?post=978"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}